{"id":16113,"date":"2023-05-17T18:40:28","date_gmt":"2023-05-17T18:40:28","guid":{"rendered":"https:\/\/www.sdg16.plus\/?post_type=policies&#038;p=16113"},"modified":"2024-12-13T14:56:34","modified_gmt":"2024-12-13T14:56:34","slug":"le-programme-argentin-de-revenu-familial-durgence-a-attenue-les-inegalites-et-la-pauvrete-au-cours-de-la-periode-covid-19","status":"publish","type":"policies","link":"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-argentin-de-revenu-familial-durgence-a-attenue-les-inegalites-et-la-pauvrete-au-cours-de-la-periode-covid-19\/","title":{"rendered":"Le programme argentin de revenu familial d&rsquo;urgence a att\u00e9nu\u00e9 les in\u00e9galit\u00e9s et la pauvret\u00e9 au cours de la p\u00e9riode COVID-19"},"content":{"rendered":"<blockquote><p>Le programme argentin de revenu familial d&rsquo;urgence (<i><em>Ingreso Familiar de Emergencia\/IFE<\/em><\/i>) a \u00e9t\u00e9 lanc\u00e9 en mars 2020 afin d&rsquo;indemniser et de prot\u00e9ger les personnes dont les revenus ont \u00e9t\u00e9 gravement r\u00e9duits ou perdus \u00e0 la suite de la pand\u00e9mie de COVID-19.<sup><a href=\"#policy-reference-1\">1<\/a><\/sup> L&rsquo;IFE consistait en des transferts d&rsquo;argent pour les ch\u00f4meurs, les travailleurs ind\u00e9pendants \u00e0 faible revenu et les travailleurs domestiques. En octobre 2020, pr\u00e8s de neuf millions de personnes avaient re\u00e7u des transferts. Le programme a permis de contenir efficacement l&rsquo;augmentation de la pauvret\u00e9 et des in\u00e9galit\u00e9s pendant la pand\u00e9mie.<\/p><\/blockquote>\n<p>Le COVID-19 et les mesures sanitaires mises en place par le gouvernement pour enrayer sa propagation ont entra\u00een\u00e9 des co\u00fbts \u00e9conomiques importants. Les activit\u00e9s de production ont \u00e9t\u00e9 suspendues et les niveaux de ch\u00f4mage et de pauvret\u00e9 ont augment\u00e9.<sup><a href=\"#policy-reference-2\">2<\/a><\/sup> Pendant la pand\u00e9mie en Argentine, le taux de ch\u00f4mage a atteint 13,1 % en 2020, contre 10,5 % l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente,<sup><a href=\"#policy-reference-3\">3<\/a><\/sup> et 41 % des m\u00e9nages ont connu une baisse de revenus<sup><a href=\"#policy-reference-4\">4<\/a><\/sup> en raison d&rsquo;une r\u00e9duction du temps de travail, d&rsquo;une contraction du niveau des ventes et\/ou de licenciements.<sup><a href=\"#policy-reference-5\">5<\/a><\/sup> Cette situation s&rsquo;est produite au milieu d&rsquo;une crise \u00e9conomique dans le pays : L&rsquo;Argentine connaissait d\u00e9j\u00e0 un ch\u00f4mage croissant, une inflation \u00e9lev\u00e9e et une \u00e9conomie en perte de vitesse avant l&rsquo;apparition du COVID-19.<sup><a href=\"#policy-reference-6\">6<\/a><\/sup><\/p>\n<p>De nombreux m\u00e9nages, en particulier ceux qui ne disposent pas d&rsquo;une \u00e9pargne importante, ont \u00e9prouv\u00e9 des difficult\u00e9s \u00e0 obtenir des moyens \u00e9conomiques suffisants pour subsister.<sup><a href=\"#policy-reference-7\">7<\/a><\/sup> Les femmes, les jeunes, les groupes \u00e0 faibles revenus et les travailleurs informels, qui \u00e9taient plus susceptibles de gagner des salaires plus bas et pour lesquels le travail \u00e0 distance n&rsquo;\u00e9tait pas une option, ont \u00e9t\u00e9 les plus durement touch\u00e9s par les circonstances.<sup><a href=\"#policy-reference-8\">8<\/a><\/sup><\/p>\n<p>Le revenu familial d&rsquo;urgence<em>(Ingreso Familiar de Emergencia ou IFE)<\/em> visait \u00e0 compenser et \u00e0 fournir une aide \u00e9conomique imm\u00e9diate aux personnes dont le revenu avait \u00e9t\u00e9 gravement r\u00e9duit ou perdu par le COVID-19.<sup><a href=\"#policy-reference-9\">9<\/a><\/sup> Le revenu familial d&rsquo;urgence consistait en trois transferts en esp\u00e8ces de 10 000 ARG chacun (environ 148 USD) accord\u00e9s \u00e0 un membre du groupe familial. Le premier versement a \u00e9t\u00e9 effectu\u00e9 en avril 2020, le deuxi\u00e8me en juin 2020 et le troisi\u00e8me en juillet de la m\u00eame ann\u00e9e. Pour en b\u00e9n\u00e9ficier, il faut \u00eatre \u00e2g\u00e9 de 18 \u00e0 65 ans et faire partie de l&rsquo;une des trois cat\u00e9gories suivantes : ch\u00f4meurs, travailleurs ind\u00e9pendants \u00e0 faibles revenus ou travailleurs domestiques.<sup><a href=\"#policy-reference-10\">10<\/a><\/sup><\/p>\n<h2><strong>Mise en \u0153uvre<\/strong><\/h2>\n<p>L&rsquo;IFE a \u00e9t\u00e9 lanc\u00e9 en avril 2020 par un d\u00e9cret pr\u00e9sidentiel (d\u00e9cret 310, 2020) et devait \u00e0 l&rsquo;origine \u00eatre un paiement unique de 10 000 ARG (environ 148 USD). La demande et le nombre de personnes enregistr\u00e9es ont largement d\u00e9pass\u00e9 les pr\u00e9visions initiales du gouvernement. En cons\u00e9quence, les d\u00e9lais d&rsquo;enregistrement ont \u00e9t\u00e9 prolong\u00e9s et deux d\u00e9crets suppl\u00e9mentaires ont \u00e9tabli de nouveaux paiements en juin et ao\u00fbt 2020.<sup><a href=\"#policy-reference-11\">11<\/a><\/sup><\/p>\n<p>Le gouvernement a permis aux m\u00e9nages et aux individus de demander des transferts en esp\u00e8ces, ce qui a facilit\u00e9 la mise en \u0153uvre efficace du programme.<sup> <a href=\"#policy-reference-12\">12<\/a><\/sup> Au cours de la premi\u00e8re phase, 2,4 millions de personnes ont re\u00e7u le paiement automatiquement en tant que b\u00e9n\u00e9ficiaires ant\u00e9rieurs de prestations d&rsquo;autres \u00c9tats.<sup><a href=\"#policy-reference-13\">13<\/a><\/sup> L&rsquo;Administration nationale de la s\u00e9curit\u00e9 sociale (ANSES) \u00e9tait l&rsquo;entit\u00e9 charg\u00e9e de recevoir et d&rsquo;\u00e9valuer les demandes.<\/p>\n<p>Cet IFE a \u00e9t\u00e9 mis en \u0153uvre, ainsi que d&rsquo;autres mesures de protection sociale telles que l&rsquo;assurance ch\u00f4mage et la protection des travailleurs formels.<sup><a href=\"#policy-reference-14\">14<\/a><\/sup> En novembre 2020, le gouvernement a mis fin \u00e0 l&rsquo;IFE, avec l&rsquo;assouplissement des mesures de confinement et une reprise \u00e9conomique progressive.<sup><a href=\"#policy-reference-15\">15<\/a><\/sup> Dans le m\u00eame temps, le gouvernement a annonc\u00e9 des mesures visant \u00e0 renforcer d&rsquo;autres programmes de protection sociale,<sup> <a href=\"#policy-reference-16\">16<\/a><\/sup> comme l&rsquo;allocation universelle pour enfant (AUH).<sup><a href=\"#policy-reference-17\">17<\/a><\/sup><\/p>\n<h2><strong>Co\u00fbt<\/strong><\/h2>\n<p>Financ\u00e9 par le Tr\u00e9sor national argentin, le programme a \u00e9t\u00e9 estim\u00e9 \u00e0 plus de 265 000 millions d&rsquo;ARG (environ 12,2 millions d&rsquo;USD),<sup><a href=\"#policy-reference-18\">18<\/a><\/sup> soit environ 1,14 % du PIB argentin.<sup><a href=\"#policy-reference-19\">19<\/a><\/sup><\/p>\n<h2><strong>L&rsquo;\u00e9valuation<\/strong><\/h2>\n<p>Neuf millions de personnes ont b\u00e9n\u00e9fici\u00e9 des transferts de l&rsquo;IFE.<sup><a href=\"#policy-reference-20\">20<\/a><\/sup> La majorit\u00e9 des b\u00e9n\u00e9ficiaires sont des ch\u00f4meurs et des travailleurs informels \u00e0 faible revenu (62 %) et des r\u00e9sidents de la zone m\u00e9tropolitaine et de la province de Buenos Aires (40 %).<sup><a href=\"#policy-reference-21\">21<\/a><\/sup> Des \u00e9tudes ont d\u00e9montr\u00e9 que le programme a effectivement att\u00e9nu\u00e9 les effets de la pand\u00e9mie sur la pauvret\u00e9 et l&rsquo;in\u00e9galit\u00e9 des revenus. Selon Calcagno, sans l&rsquo;IFE, 1,4 million de personnes seraient tomb\u00e9es dans la pauvret\u00e9 et 2,8 millions dans l&rsquo;extr\u00eame pauvret\u00e9.<sup><a href=\"#policy-reference-22\">22<\/a><\/sup> Si l&rsquo;IFE n&rsquo;avait pas \u00e9t\u00e9 mis en \u0153uvre, la pauvret\u00e9 nationale aurait pu passer d&rsquo;environ 36 % \u00e0 44 %.<sup><a href=\"#policy-reference-23\">23<\/a><\/sup><\/p>\n<p>Une \u00e9valuation r\u00e9alis\u00e9e par le gouvernement a montr\u00e9 que les habitants des barrios populares &#8211; quartiers o\u00f9 l&rsquo;habitat est informel et l&rsquo;acc\u00e8s aux services publics limit\u00e9 &#8211; avaient une perception positive du programme. Ils ont consid\u00e9r\u00e9 l&rsquo;IFE comme une mesure essentielle au pire moment de la crise COVID-19. Les r\u00e9sidents ont affirm\u00e9 avoir utilis\u00e9 l&rsquo;argent liquide pour acheter de la nourriture, effectuer des r\u00e9parations urgentes \u00e0 leur domicile et rembourser leurs dettes.<sup><a href=\"#policy-reference-24\">24<\/a><\/sup><\/p>\n<p>Il y a \u00e9galement eu d&rsquo;autres effets inattendus. L&rsquo;IFE a suscit\u00e9 un d\u00e9bat national sur l&rsquo;opportunit\u00e9 d&rsquo;un revenu de base universel permanent, compte tenu des niveaux \u00e9lev\u00e9s d&rsquo;informalit\u00e9 dans le pays. Elle a \u00e9galement suscit\u00e9 des mesures similaires dans d&rsquo;autres pays de la r\u00e9gion : par exemple, le Chili a mis en place son propre revenu familial d&rsquo;urgence en mai 2020.<sup><a href=\"#policy-reference-25\">25<\/a><\/sup><\/p>\n","protected":false},"template":"","categories":[321],"tags":[821,907,678,680,725,684,676,695,677,704],"class_list":["post-16113","policies","type-policies","status-publish","hentry","category-non-classifiee","tag-amerique-latine-et-caraibes","tag-argentine","tag-enfants-et-jeunes","tag-genre","tag-groupes-a-faibles-revenus","tag-pays-a-revenu-intermediaire","tag-protection-sociale","tag-revenu-et-richesse","tag-sante","tag-travail","policy-regions-latin-america-the-caribbean"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le programme argentin de revenu familial d&#039;urgence a att\u00e9nu\u00e9 les in\u00e9galit\u00e9s et la pauvret\u00e9 au cours de la p\u00e9riode COVID-19 - Pathfinders<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-argentin-de-revenu-familial-durgence-a-attenue-les-inegalites-et-la-pauvrete-au-cours-de-la-periode-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le programme argentin de revenu familial d&#039;urgence a att\u00e9nu\u00e9 les in\u00e9galit\u00e9s et la pauvret\u00e9 au cours de la p\u00e9riode COVID-19 - Pathfinders\" \/>\n<meta property=\"og:description\" content=\"Le programme argentin de revenu familial d&rsquo;urgence (Ingreso Familiar de Emergencia\/IFE) a \u00e9t\u00e9 lanc\u00e9 en mars 2020 afin d&rsquo;indemniser et de prot\u00e9ger les personnes dont les revenus ont \u00e9t\u00e9 gravement r\u00e9duits ou perdus \u00e0 la suite de la pand\u00e9mie de COVID-19.1 L&rsquo;IFE consistait en des transferts d&rsquo;argent pour les ch\u00f4meurs, les travailleurs ind\u00e9pendants \u00e0 faible\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-argentin-de-revenu-familial-durgence-a-attenue-les-inegalites-et-la-pauvrete-au-cours-de-la-periode-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Pathfinders\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-13T14:56:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/le-programme-argentin-de-revenu-familial-durgence-a-attenue-les-inegalites-et-la-pauvrete-au-cours-de-la-periode-covid-19\\\/\",\"url\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/le-programme-argentin-de-revenu-familial-durgence-a-attenue-les-inegalites-et-la-pauvrete-au-cours-de-la-periode-covid-19\\\/\",\"name\":\"Le programme argentin de revenu familial d'urgence a att\u00e9nu\u00e9 les in\u00e9galit\u00e9s et la pauvret\u00e9 au cours de la p\u00e9riode COVID-19 - Pathfinders\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/#website\"},\"datePublished\":\"2023-05-17T18:40:28+00:00\",\"dateModified\":\"2024-12-13T14:56:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/le-programme-argentin-de-revenu-familial-durgence-a-attenue-les-inegalites-et-la-pauvrete-au-cours-de-la-periode-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/le-programme-argentin-de-revenu-familial-durgence-a-attenue-les-inegalites-et-la-pauvrete-au-cours-de-la-periode-covid-19\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/le-programme-argentin-de-revenu-familial-durgence-a-attenue-les-inegalites-et-la-pauvrete-au-cours-de-la-periode-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le programme argentin de revenu familial d&#8217;urgence a att\u00e9nu\u00e9 les in\u00e9galit\u00e9s et la pauvret\u00e9 au cours de la p\u00e9riode COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/\",\"name\":\"Pathfinders\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le programme argentin de revenu familial d'urgence a att\u00e9nu\u00e9 les in\u00e9galit\u00e9s et la pauvret\u00e9 au cours de la p\u00e9riode COVID-19 - Pathfinders","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-argentin-de-revenu-familial-durgence-a-attenue-les-inegalites-et-la-pauvrete-au-cours-de-la-periode-covid-19\/","og_locale":"fr_FR","og_type":"article","og_title":"Le programme argentin de revenu familial d'urgence a att\u00e9nu\u00e9 les in\u00e9galit\u00e9s et la pauvret\u00e9 au cours de la p\u00e9riode COVID-19 - Pathfinders","og_description":"Le programme argentin de revenu familial d&rsquo;urgence (Ingreso Familiar de Emergencia\/IFE) a \u00e9t\u00e9 lanc\u00e9 en mars 2020 afin d&rsquo;indemniser et de prot\u00e9ger les personnes dont les revenus ont \u00e9t\u00e9 gravement r\u00e9duits ou perdus \u00e0 la suite de la pand\u00e9mie de COVID-19.1 L&rsquo;IFE consistait en des transferts d&rsquo;argent pour les ch\u00f4meurs, les travailleurs ind\u00e9pendants \u00e0 faible","og_url":"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-argentin-de-revenu-familial-durgence-a-attenue-les-inegalites-et-la-pauvrete-au-cours-de-la-periode-covid-19\/","og_site_name":"Pathfinders","article_modified_time":"2024-12-13T14:56:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-argentin-de-revenu-familial-durgence-a-attenue-les-inegalites-et-la-pauvrete-au-cours-de-la-periode-covid-19\/","url":"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-argentin-de-revenu-familial-durgence-a-attenue-les-inegalites-et-la-pauvrete-au-cours-de-la-periode-covid-19\/","name":"Le programme argentin de revenu familial d'urgence a att\u00e9nu\u00e9 les in\u00e9galit\u00e9s et la pauvret\u00e9 au cours de la p\u00e9riode COVID-19 - Pathfinders","isPartOf":{"@id":"https:\/\/www.sdg16.plus\/fr\/#website"},"datePublished":"2023-05-17T18:40:28+00:00","dateModified":"2024-12-13T14:56:34+00:00","breadcrumb":{"@id":"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-argentin-de-revenu-familial-durgence-a-attenue-les-inegalites-et-la-pauvrete-au-cours-de-la-periode-covid-19\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-argentin-de-revenu-familial-durgence-a-attenue-les-inegalites-et-la-pauvrete-au-cours-de-la-periode-covid-19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-argentin-de-revenu-familial-durgence-a-attenue-les-inegalites-et-la-pauvrete-au-cours-de-la-periode-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sdg16.plus\/fr\/"},{"@type":"ListItem","position":2,"name":"Le programme argentin de revenu familial d&#8217;urgence a att\u00e9nu\u00e9 les in\u00e9galit\u00e9s et la pauvret\u00e9 au cours de la p\u00e9riode COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/www.sdg16.plus\/fr\/#website","url":"https:\/\/www.sdg16.plus\/fr\/","name":"Pathfinders","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sdg16.plus\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/policies\/16113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/policies"}],"about":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/types\/policies"}],"wp:attachment":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/media?parent=16113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/categories?post=16113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/tags?post=16113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}