{"id":16108,"date":"2023-05-17T16:11:56","date_gmt":"2023-05-17T16:11:56","guid":{"rendered":"https:\/\/www.sdg16.plus\/?post_type=policies&#038;p=16108"},"modified":"2024-12-13T14:56:38","modified_gmt":"2024-12-13T14:56:38","slug":"le-programme-covid-19-de-transferts-monetaires-quasi-universels-du-timor-oriental-soutient-les-menages","status":"publish","type":"policies","link":"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-covid-19-de-transferts-monetaires-quasi-universels-du-timor-oriental-soutient-les-menages\/","title":{"rendered":"Le programme COVID-19 de transferts mon\u00e9taires quasi universels du Timor-Oriental soutient les m\u00e9nages"},"content":{"rendered":"<blockquote><p>Le gouvernement du Timor-Leste a mis en place le premier transfert mon\u00e9taire quasi universel du pays, d&rsquo;un montant de 200 USD, en avril 2020, afin d&rsquo;aider la population \u00e0 faire face aux cons\u00e9quences de la crise du COVID-19. Le transfert a \u00e9t\u00e9 accord\u00e9 \u00e0 tous les m\u00e9nages dont le revenu mensuel \u00e9tait inf\u00e9rieur \u00e0 500 USD. Cette politique a \u00e9t\u00e9 bien accueillie et a permis d&rsquo;accro\u00eetre le soutien \u00e0 la protection sociale universelle au Timor oriental. Plus des trois quarts des personnes interrog\u00e9es se sont d\u00e9clar\u00e9es satisfaites ou tr\u00e8s satisfaites de la r\u00e9ponse apport\u00e9e par le gouvernement dans le cadre du projet COVID-19.<\/p><\/blockquote>\n<p>Le 28 mars 2020, le gouvernement du Timor-Leste a annonc\u00e9 l&rsquo;\u00e9tat d&rsquo;urgence en r\u00e9ponse \u00e0 la pand\u00e9mie de COVID-19, impliquant des restrictions de voyage, une distanciation sociale et des fermetures d&rsquo;\u00e9coles. Les perturbations caus\u00e9es par la pand\u00e9mie devraient avoir des r\u00e9percussions n\u00e9gatives consid\u00e9rables sur les moyens de subsistance et les strat\u00e9gies de survie des habitants du pays, en particulier ceux qui vivent dans la pauvret\u00e9 ou la quasi-pauvret\u00e9. Parmi les mesures de soutien mises en place pour aider les gens \u00e0 faire face \u00e0 ces perturbations, le gouvernement a annonc\u00e9 un transfert universel inconditionnel d&rsquo;argent liquide pour tous les m\u00e9nages ne disposant pas d&rsquo;un revenu mensuel individuel r\u00e9gulier de 500 USD. Le transfert a touch\u00e9 environ 300 000 m\u00e9nages dans les 452 villages du pays.<\/p>\n<p>L&rsquo;approche universelle a \u00e9t\u00e9 adopt\u00e9e pour \u00e9viter les exclusions qui pourraient se produire dans le cadre d&rsquo;une approche cibl\u00e9e de la protection sociale. Un registre national existant a \u00e9t\u00e9 utilis\u00e9, mais les personnes ont \u00e9t\u00e9 invit\u00e9es \u00e0 s&rsquo;inscrire au registre pour recevoir le paiement. Malgr\u00e9 l&rsquo;approche universelle du transfert, certaines exclusions importantes ont \u00e9t\u00e9 constat\u00e9es. Les femmes h\u00e9berg\u00e9es n&rsquo;ont pas \u00e9t\u00e9 touch\u00e9es par les transferts et certaines personnes n&rsquo;ont pas \u00e9t\u00e9 reconnues par les autorit\u00e9s locales.<sup><a href=\"#policy-reference-1\">1<\/a><\/sup> Une enqu\u00eate a r\u00e9v\u00e9l\u00e9 que les personnes LGBTI interrog\u00e9es ne s&rsquo;enregistraient pas ou n&rsquo;enregistraient pas leur famille en raison des conseils des autorit\u00e9s locales ou d&rsquo;une perception r\u00e9pandue selon laquelle les personnes vivant seules ou dans des couples de m\u00eame sexe n&rsquo;\u00e9taient pas consid\u00e9r\u00e9es comme un m\u00e9nage.<sup><a href=\"#policy-reference-2\">2<\/a><\/sup><\/p>\n<p>Dans l&rsquo;ensemble, la politique a \u00e9t\u00e9 bien accueillie, tout en tenant compte de ces exclusions. Fort du succ\u00e8s de cette politique, le gouvernement du Timor-Leste a annonc\u00e9 d&rsquo;autres transferts mon\u00e9taires universels, notamment un transfert pilote pour tous les enfants, les femmes enceintes et les enfants handicap\u00e9s dans trois municipalit\u00e9s, qui sera \u00e9tendu \u00e0 l&rsquo;ensemble du pays d&rsquo;ici 2028.<\/p>\n<h2><strong>Mise en \u0153uvre<\/strong><\/h2>\n<p>L&rsquo;identification des m\u00e9nages \u00e9ligibles s&rsquo;est faite par le biais d&rsquo;un syst\u00e8me existant d&rsquo;enregistrement des m\u00e9nages, Ficha de Familia, g\u00e9r\u00e9 par le minist\u00e8re de l&rsquo;administration de l&rsquo;\u00c9tat. Ce syst\u00e8me d&rsquo;enregistrement des m\u00e9nages avait \u00e9t\u00e9 mis en place pour enregistrer les m\u00e9nages dans le cadre du Programme national de d\u00e9veloppement des villages (PNDS). Les nouveaux enregistrements ont \u00e9t\u00e9 invit\u00e9s \u00e0 se faire pendant une \u00ab\u00a0p\u00e9riode de gr\u00e2ce\u00a0\u00bb allant jusqu&rsquo;au 31 mars 2020.<\/p>\n<p>Le transfert unique d&rsquo;urgence de 200 USD a \u00e9t\u00e9 vers\u00e9 directement aux chefs de m\u00e9nage sur une p\u00e9riode de 30 jours \u00e0 partir de juin 2020. Les paiements ont \u00e9t\u00e9 distribu\u00e9s en personne sur les sites de collecte dans chaque village par le personnel du minist\u00e8re de la Solidarit\u00e9 sociale et de l&rsquo;Inclusion et par les chefs de village. Des paiements ont \u00e9galement \u00e9t\u00e9 effectu\u00e9s \u00e0 la \u00ab\u00a0porte\u00a0\u00bb des personnes qui ne pouvaient pas se rendre au lieu de collecte, comme les personnes \u00e2g\u00e9es et les personnes souffrant d&rsquo;un handicap physique.<sup><a href=\"#policy-reference-3\">3<\/a><\/sup> Les paiements ont \u00e9t\u00e9 effectu\u00e9s principalement aux hommes chefs de famille, bien qu&rsquo;une \u00e9tude ait r\u00e9v\u00e9l\u00e9 que les d\u00e9cisions de d\u00e9penses des m\u00e9nages \u00e9taient largement prises par les hommes et les femmes ensemble et a sugg\u00e9r\u00e9 que la remise en question des normes de genre li\u00e9es aux d\u00e9penses des m\u00e9nages n&rsquo;est peut-\u00eatre pas appropri\u00e9e en temps de crise.<sup><a href=\"#policy-reference-4\">4<\/a><\/sup><\/p>\n<h2><strong>Co\u00fbt<\/strong><\/h2>\n<p>Le co\u00fbt du transfert universel d&rsquo;argent de secours COVID-19 est estim\u00e9 \u00e0 60 millions d&rsquo;USD. Le programme a \u00e9t\u00e9 financ\u00e9 par un fonds COVID-19 plus large de 250 millions d&rsquo;USD \u00e9tabli en avril 2020 et a impliqu\u00e9 un transfert du fonds p\u00e9trolier du Timor-Leste.<sup><a href=\"#policy-reference-5\">5<\/a><\/sup><\/p>\n<h2><strong>L&rsquo;\u00e9valuation<\/strong><\/h2>\n<p>Le transfert universel a \u00e9t\u00e9 \u00e9tudi\u00e9 par une s\u00e9rie d&rsquo;institutions et s&rsquo;est av\u00e9r\u00e9 globalement efficace pour att\u00e9nuer certaines des cons\u00e9quences \u00e9conomiques les plus graves de la crise du COVID-19 sur les personnes vivant dans la pauvret\u00e9 ou proches de la pauvret\u00e9 au Timor-Oriental. On estime que 95 % des personnes ont re\u00e7u le transfert d&rsquo;argent et\/ou un transfert de nourriture compl\u00e9mentaire.<sup><a href=\"#policy-reference-6\">6<\/a><\/sup> Les personnes vivant en dehors de la capitale, o\u00f9 les taux de pauvret\u00e9 sont plus \u00e9lev\u00e9s, \u00e9taient plus susceptibles de recevoir le transfert, ce qui sugg\u00e8re que la politique \u00e9tait progressive. Une enqu\u00eate a r\u00e9v\u00e9l\u00e9 que 96,9 % des b\u00e9n\u00e9ficiaires ont d\u00e9pens\u00e9 le transfert en nourriture et boissons non alcoolis\u00e9es, 27,6 % en v\u00eatements et chaussures, et 16,9 % en sant\u00e9 et \u00e9ducation.<sup><a href=\"#policy-reference-7\">7<\/a><\/sup> Une enqu\u00eate men\u00e9e aupr\u00e8s de travailleurs ind\u00e9pendants et de propri\u00e9taires de petites entreprises a \u00e9galement r\u00e9v\u00e9l\u00e9 que 78 % d&rsquo;entre eux ont observ\u00e9 une augmentation de leurs ventes \u00e0 la suite des transferts et que 80 % ont obtenu de meilleurs prix pour leurs produits.<sup><a href=\"#policy-reference-8\">8<\/a><\/sup> Le transfert universel a \u00e9galement \u00e9t\u00e9 attribu\u00e9 \u00e0 un changement positif dans les relations communautaires. Avant le transfert, 70 % de la population pensait que COVID-19 avait rapproch\u00e9 leur communaut\u00e9, et ce chiffre est pass\u00e9 \u00e0 82 % apr\u00e8s le transfert.<sup><a href=\"#policy-reference-9\">9<\/a><\/sup> Il a \u00e9t\u00e9 difficile d&rsquo;atteindre les personnes en situation d&rsquo;exclusion sociale, en particulier celles qui ne correspondent pas aux normes sociales des structures familiales typiques, notamment les m\u00e8res c\u00e9libataires, les veuves, les personnes handicap\u00e9es, les personnes LGBT, les survivants de violences et les travailleurs domestiques.<sup><a href=\"#policy-reference-10\">10<\/a><\/sup><\/p>\n<p><em>Toutes les opinions et tous les points de vue exprim\u00e9s sur ce site Internet repr\u00e9sentent uniquement les points de vue des auteurs et de Pathfinders for Peaceful, Just and Inclusive Societies, un programme du Center on International Cooperation de l&rsquo;Universit\u00e9 de New York. Les opinions exprim\u00e9es ne refl\u00e8tent pas n\u00e9cessairement celles de la Commission \u00e9conomique et sociale des Nations unies pour l&rsquo;Asie occidentale.<\/em><\/p>\n","protected":false},"template":"","categories":[321],"tags":[726,725,684,676,697,695,677,906,703],"class_list":["post-16108","policies","type-policies","status-publish","hentry","category-non-classifiee","tag-asie-et-pacifique","tag-groupes-a-faibles-revenus","tag-pays-a-revenu-intermediaire","tag-protection-sociale","tag-redistribution-fr","tag-revenu-et-richesse","tag-sante","tag-timor-leste-fr","tag-universel","policy-regions-asia-pacific"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transfert universel d&#039;esp\u00e8ces COVID-19 : Timor-Leste | Solutions aux in\u00e9galit\u00e9s<\/title>\n<meta name=\"description\" content=\"Le Timor-Leste a mis en place le premier transfert d&#039;argent quasi universel du pays en avril 2020 pour aider la population \u00e0 faire face aux cons\u00e9quences du COVID-19.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-covid-19-de-transferts-monetaires-quasi-universels-du-timor-oriental-soutient-les-menages\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transfert universel d&#039;esp\u00e8ces COVID-19 : Timor-Leste | Solutions aux in\u00e9galit\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Le Timor-Leste a mis en place le premier transfert d&#039;argent quasi universel du pays en avril 2020 pour aider la population \u00e0 faire face aux cons\u00e9quences du COVID-19.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-covid-19-de-transferts-monetaires-quasi-universels-du-timor-oriental-soutient-les-menages\/\" \/>\n<meta property=\"og:site_name\" content=\"Pathfinders\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-13T14:56:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/le-programme-covid-19-de-transferts-monetaires-quasi-universels-du-timor-oriental-soutient-les-menages\\\/\",\"url\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/le-programme-covid-19-de-transferts-monetaires-quasi-universels-du-timor-oriental-soutient-les-menages\\\/\",\"name\":\"Transfert universel d'esp\u00e8ces COVID-19 : Timor-Leste | Solutions aux in\u00e9galit\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/#website\"},\"datePublished\":\"2023-05-17T16:11:56+00:00\",\"dateModified\":\"2024-12-13T14:56:38+00:00\",\"description\":\"Le Timor-Leste a mis en place le premier transfert d'argent quasi universel du pays en avril 2020 pour aider la population \u00e0 faire face aux cons\u00e9quences du COVID-19.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/le-programme-covid-19-de-transferts-monetaires-quasi-universels-du-timor-oriental-soutient-les-menages\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/le-programme-covid-19-de-transferts-monetaires-quasi-universels-du-timor-oriental-soutient-les-menages\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/le-programme-covid-19-de-transferts-monetaires-quasi-universels-du-timor-oriental-soutient-les-menages\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le programme COVID-19 de transferts mon\u00e9taires quasi universels du Timor-Oriental soutient les m\u00e9nages\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/\",\"name\":\"Pathfinders\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transfert universel d'esp\u00e8ces COVID-19 : Timor-Leste | Solutions aux in\u00e9galit\u00e9s","description":"Le Timor-Leste a mis en place le premier transfert d'argent quasi universel du pays en avril 2020 pour aider la population \u00e0 faire face aux cons\u00e9quences du COVID-19.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-covid-19-de-transferts-monetaires-quasi-universels-du-timor-oriental-soutient-les-menages\/","og_locale":"fr_FR","og_type":"article","og_title":"Transfert universel d'esp\u00e8ces COVID-19 : Timor-Leste | Solutions aux in\u00e9galit\u00e9s","og_description":"Le Timor-Leste a mis en place le premier transfert d'argent quasi universel du pays en avril 2020 pour aider la population \u00e0 faire face aux cons\u00e9quences du COVID-19.","og_url":"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-covid-19-de-transferts-monetaires-quasi-universels-du-timor-oriental-soutient-les-menages\/","og_site_name":"Pathfinders","article_modified_time":"2024-12-13T14:56:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-covid-19-de-transferts-monetaires-quasi-universels-du-timor-oriental-soutient-les-menages\/","url":"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-covid-19-de-transferts-monetaires-quasi-universels-du-timor-oriental-soutient-les-menages\/","name":"Transfert universel d'esp\u00e8ces COVID-19 : Timor-Leste | Solutions aux in\u00e9galit\u00e9s","isPartOf":{"@id":"https:\/\/www.sdg16.plus\/fr\/#website"},"datePublished":"2023-05-17T16:11:56+00:00","dateModified":"2024-12-13T14:56:38+00:00","description":"Le Timor-Leste a mis en place le premier transfert d'argent quasi universel du pays en avril 2020 pour aider la population \u00e0 faire face aux cons\u00e9quences du COVID-19.","breadcrumb":{"@id":"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-covid-19-de-transferts-monetaires-quasi-universels-du-timor-oriental-soutient-les-menages\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-covid-19-de-transferts-monetaires-quasi-universels-du-timor-oriental-soutient-les-menages\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sdg16.plus\/fr\/policies\/le-programme-covid-19-de-transferts-monetaires-quasi-universels-du-timor-oriental-soutient-les-menages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sdg16.plus\/fr\/"},{"@type":"ListItem","position":2,"name":"Le programme COVID-19 de transferts mon\u00e9taires quasi universels du Timor-Oriental soutient les m\u00e9nages"}]},{"@type":"WebSite","@id":"https:\/\/www.sdg16.plus\/fr\/#website","url":"https:\/\/www.sdg16.plus\/fr\/","name":"Pathfinders","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sdg16.plus\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/policies\/16108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/policies"}],"about":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/types\/policies"}],"wp:attachment":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/media?parent=16108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/categories?post=16108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/tags?post=16108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}