{"id":16069,"date":"2023-04-21T14:45:45","date_gmt":"2023-04-21T14:45:45","guid":{"rendered":"https:\/\/www.sdg16.plus\/?post_type=policies&#038;p=16069"},"modified":"2024-12-12T15:04:55","modified_gmt":"2024-12-12T15:04:55","slug":"programme-libanais-deducation-inclusive-pour-les-enfants-handicapes","status":"publish","type":"policies","link":"https:\/\/www.sdg16.plus\/fr\/policies\/programme-libanais-deducation-inclusive-pour-les-enfants-handicapes\/","title":{"rendered":"Programme libanais d&rsquo;\u00e9ducation inclusive pour les enfants handicap\u00e9s"},"content":{"rendered":"<blockquote><p>Conform\u00e9ment \u00e0 la strat\u00e9gie d&rsquo;inclusion du minist\u00e8re libanais de l&rsquo;\u00c9ducation et de l&rsquo;Enseignement sup\u00e9rieur (MEHE) de 2012, un programme pilote d&rsquo;\u00e9ducation inclusive (IE) a \u00e9t\u00e9 lanc\u00e9 en 2018, couvrant 30 \u00e9coles publiques des cinq gouvernorats libanais. Le programme visait \u00e0 promouvoir l&rsquo;int\u00e9gration des enfants handicap\u00e9s dans l&rsquo;enseignement ordinaire (c&rsquo;est-\u00e0-dire ceux qui pr\u00e9sentent des d\u00e9ficiences physiques, mentales, intellectuelles ou sensorielles \u00e0 long terme qui, en interaction avec diverses barri\u00e8res, peuvent entraver leur participation pleine et effective \u00e0 la soci\u00e9t\u00e9 sur un pied d&rsquo;\u00e9galit\u00e9).<sup><a href=\"#policy-reference-1\">1<\/a><\/sup><\/p><\/blockquote>\n<p>Avant le programme, les enfants handicap\u00e9s au Liban \u00e9taient plus susceptibles de recevoir peu d&rsquo;\u00e9ducation formelle ou d&rsquo;\u00eatre enseign\u00e9s dans des institutions sp\u00e9cialis\u00e9es que dans le syst\u00e8me \u00e9ducatif g\u00e9n\u00e9ral, ce qui a contribu\u00e9 \u00e0 promouvoir une culture d&rsquo;exclusion et de s\u00e9gr\u00e9gation \u00e0 l&rsquo;\u00e9gard des personnes handicap\u00e9es.<a href=\"#policy-reference-2\"><sup>2<\/sup><\/a><\/p>\n<p>Le MEHE a lanc\u00e9 une strat\u00e9gie d&rsquo;inclusion en 2012,<sup><a href=\"#policy-reference-3\">3<\/a> <\/sup>mais le manque de financement a entrav\u00e9 sa mise en \u0153uvre.<\/p>\n<h2><b><hgroup class=\"section-group\"><svg class='section-group__icon' aria-hidden='true' slot='caret'><use xlink:href='#sprite-implementation'><\/use><\/svg><h2 class='section-group__heading'><\/b><b>Mise en \u0153uvre<\/b><b><\/h2><\/hgroup><\/b><\/h2>\n<p>En 2018, le MEHE a lanc\u00e9 la mise en \u0153uvre de la strat\u00e9gie d&rsquo;inclusion par le biais d&rsquo;un programme pilote d&rsquo;IE financ\u00e9 par des donateurs. Les 30 \u00e9coles publiques concern\u00e9es ont \u00e9t\u00e9 choisies en fonction de leur r\u00e9partition g\u00e9ographique dans les cinq gouvernorats libanais, afin qu&rsquo;elles soient accessibles au plus grand nombre possible d&rsquo;enfants handicap\u00e9s. Le programme IE visait \u00e0 inscrire les enfants handicap\u00e9s dans les \u00e9coles publiques et \u00e0 renforcer la capacit\u00e9 du syst\u00e8me \u00e9ducatif et des communaut\u00e9s \u00e0 fournir une \u00e9ducation inclusive. Les enfants handicap\u00e9s \u00e9taient accept\u00e9s sans condition dans ces 30 \u00e9coles et se voyaient attribuer des places dans les classes ordinaires, mais leur acc\u00e8s aux services sp\u00e9cialis\u00e9s pour les personnes handicap\u00e9es au sein de l&rsquo;\u00e9cole n\u00e9cessitait l&rsquo;\u00e9valuation d&rsquo;un m\u00e9decin ou d&rsquo;un psychologue.<\/p>\n<p>Dans le cadre de ce programme, 30 \u00e9ducateurs sp\u00e9cialis\u00e9s \u00e0 temps plein, un par \u00e9cole, et une \u00e9quipe de sp\u00e9cialistes \u00e0 temps partiel (psychologues, psychomotriciens et orthophonistes) fournissent un soutien \u00e9ducatif sp\u00e9cialis\u00e9. Le Centre pour la recherche et le d\u00e9veloppement de l&rsquo;\u00e9ducation (CERD) et la facult\u00e9 d&rsquo;\u00e9ducation de l&rsquo;universit\u00e9 libanaise ont form\u00e9 des enseignants et des directeurs d&rsquo;\u00e9cole \u00e0 l&rsquo;\u00e9ducation inclusive, notamment \u00e0 la m\u00e9thodologie MTSS (Multi-Tiered System of Supports) et \u00e0 l&rsquo;enseignement diff\u00e9renci\u00e9 (le\u00e7ons adapt\u00e9es aux besoins de l&rsquo;\u00e9l\u00e8ve).<\/p>\n<p>Une unit\u00e9 charg\u00e9e des besoins \u00e9ducatifs sp\u00e9ciaux a \u00e9t\u00e9 cr\u00e9\u00e9e au sein du MEHE pour assurer le suivi du programme et \u00e9laborer des supports de formation pour les enseignants, tels que des guides d&rsquo;enseignement pour l&rsquo;infirmit\u00e9 motrice c\u00e9r\u00e9brale, le spectre autistique et les troubles du d\u00e9veloppement intellectuel. Un syst\u00e8me d&rsquo;orientation a \u00e9t\u00e9 mis en place pour garantir que les enfants handicap\u00e9s puissent avoir acc\u00e8s aux services d&rsquo;intervention et \u00e0 l&rsquo;\u00e9quipement si n\u00e9cessaire (fournitures techniques, appareils d&rsquo;assistance).<\/p>\n<p>Des sessions de sensibilisation ont \u00e9t\u00e9 organis\u00e9es pour la communaut\u00e9 et les parents afin de pr\u00e9senter le concept d&rsquo;\u00e9ducation inclusive, l&rsquo;impact positif qu&rsquo;elle a sur les apprenants et la communaut\u00e9, et les droits des enfants handicap\u00e9s.<\/p>\n<h2><b><hgroup class=\"section-group\"><svg class='section-group__icon' aria-hidden='true' slot='caret'><use xlink:href='#sprite-cost'><\/use><\/svg><h2 class='section-group__heading'><\/b><b>Co\u00fbt<\/b><b><\/h2><\/hgroup><\/b><\/h2>\n<p>Le programme fait partie d&rsquo;un projet plus large de 15 millions de dollars intitul\u00e9 \u00ab\u00a0Acc\u00e8s \u00e0 l&rsquo;\u00e9ducation et apprentissage de qualit\u00e9 au Liban\u00a0\u00bb, financ\u00e9 par le gouvernement canadien et mis en \u0153uvre par l&rsquo;UNICEF. Le montant d\u00e9bours\u00e9 pour le programme d&rsquo;\u00e9ducation inclusive n&rsquo;est pas clair.<sup><a href=\"#policy-reference-4\">4<\/a><\/sup><\/p>\n<h2><b><hgroup class=\"section-group\"><svg class='section-group__icon' aria-hidden='true' slot='caret'><use xlink:href='#sprite-assessment'><\/use><\/svg><h2 class='section-group__heading'><\/b><b>L'\u00e9valuation<\/b><b><\/h2><\/hgroup><\/b><\/h2>\n<p>Les 30 \u00e9coles ont b\u00e9n\u00e9fici\u00e9 d&rsquo;\u00e9ducateurs sp\u00e9cialis\u00e9s, d&rsquo;\u00e9quipements et de services sp\u00e9cialis\u00e9s, ainsi que d&rsquo;enseignants mieux form\u00e9s aux pratiques d&rsquo;\u00e9ducation inclusive. Les initiatives de sensibilisation et d&rsquo;engagement communautaires ont touch\u00e9 plus de 3 500 personnes, et 5 910 enfants handicap\u00e9s ont b\u00e9n\u00e9fici\u00e9 d&rsquo;un soutien pour s&rsquo;inscrire dans l&rsquo;enseignement, tant formel que non formel (c&rsquo;est-\u00e0-dire des voyages scolaires, des activit\u00e9s apr\u00e8s l&rsquo;\u00e9cole et des interactions sociales).<sup><a href=\"#policy-reference-5\">5<\/a><\/sup><\/p>\n<p>Une \u00e9valuation de l&rsquo;UNICEF r\u00e9alis\u00e9e en 2021 a soulign\u00e9 qu&rsquo;avec le soutien sp\u00e9cialis\u00e9 propos\u00e9, les \u00e9coles pilotes avaient \u00e9t\u00e9 en mesure d&rsquo;adopter des politiques d&rsquo;inclusion (c&rsquo;est-\u00e0-dire le MTSS et l&rsquo;enseignement diff\u00e9renci\u00e9 mentionn\u00e9s ci-dessus). En cons\u00e9quence, pour l&rsquo;ann\u00e9e scolaire 2019-20, les 30 \u00e9coles publiques cibl\u00e9es comptaient 1 547 \u00e9l\u00e8ves (59 % de gar\u00e7ons, 41 % de filles) en situation de handicap inscrits dans des classes publiques, contre 1 147 pour l&rsquo;ann\u00e9e scolaire 2018-19. 75 % des apprenants nouvellement inscrits avaient des difficult\u00e9s d&rsquo;apprentissage, 18 % des difficult\u00e9s de comportement et 5 % des d\u00e9ficiences intellectuelles.<\/p>\n<p>Pendant la pand\u00e9mie de COVID-19, le programme a \u00e9t\u00e9 adapt\u00e9 pour fournir un apprentissage \u00e0 distance inclusif, tel que des vid\u00e9os et des fichiers audio adapt\u00e9s \u00e0 diff\u00e9rents types de handicaps, qui ont \u00e9t\u00e9 distribu\u00e9s via Microsoft Teams, WhatsApp, des appels vocaux et des courriels. Le processus d&rsquo;adaptation a fait l&rsquo;objet d&rsquo;un suivi attentif au moyen de journaux hebdomadaires.<sup><a href=\"#policy-reference-6\">6<\/a> <\/sup>Malgr\u00e9 le plan de gestion de crise pour l&rsquo;\u00e9ducation inclusive, de nombreux enfants handicap\u00e9s ont encore abandonn\u00e9 l&rsquo;\u00e9cole.<sup><a href=\"#policy-reference-7\">7<\/a> <\/sup> En outre, en raison de la crise \u00e9conomique, de nombreuses familles n&rsquo;avaient plus les moyens d&rsquo;envoyer leurs enfants \u00e0 l&rsquo;\u00e9cole : en 2022, 72 % des parents ont d\u00e9clar\u00e9 qu&rsquo;ils ne pouvaient pas payer l&rsquo;\u00e9ducation de leurs enfants, ce qui a entra\u00een\u00e9 une baisse de la scolarisation de 60 % de tous les enfants d&rsquo;\u00e2ge scolaire en 2020-21 \u00e0 43 % en 2021-22.<sup><a href=\"#policy-reference-8\">8<\/a><\/sup><\/p>\n<p>En 2021, en raison du succ\u00e8s du projet pilote, le Bureau des affaires \u00e9trang\u00e8res, du Commonwealth et du d\u00e9veloppement du Royaume-Uni a financ\u00e9 l&rsquo;extension du projet pilote \u00e0 60 \u00e9coles (les \u00e9valuations ne sont pas encore disponibles). Le MEHE pr\u00e9voit de transformer progressivement toutes les \u00e9coles publiques en \u00e9coles inclusives dans le cadre de l&rsquo;Agenda 2030.<sup><a href=\"#policy-reference-9\">9<\/a><\/sup> Cependant, compte tenu de la crise \u00e9conomique extr\u00eame \u00e0 laquelle le Liban a commenc\u00e9 \u00e0 faire face en 2019, la capacit\u00e9 \u00e0 d\u00e9ployer le programme \u00e0 l&rsquo;\u00e9chelle nationale d\u00e9pend du financement des donateurs.<\/p>\n<h3><strong>Informations compl\u00e9mentaires<\/strong><\/h3>\n<p>Le Liban a \u00e9t\u00e9 l&rsquo;un des premiers pays \u00e0 signer la Convention relative aux droits des personnes handicap\u00e9es (CDPH) en 2007, mais il doit encore la ratifier pour garantir leur inclusion.<\/p>\n<p>Les r\u00e9sultats du programme seront utilis\u00e9s pour informer la future politique libanaise d&rsquo;\u00e9ducation inclusive.<sup><a href=\"#policy-reference-10\">10<\/a><\/sup><\/p>\n<p>L&rsquo;\u00e9tude a \u00e9galement montr\u00e9 que les enseignants et les parents avaient largement adh\u00e9r\u00e9 \u00e0 l&rsquo;id\u00e9e de l&rsquo;\u00e9ducation inclusive, m\u00eame s&rsquo;ils ne comprenaient pas toujours parfaitement le concept.<\/p>\n<p>Des proc\u00e9dures op\u00e9rationnelles standard ont \u00e9t\u00e9 adopt\u00e9es pour assurer la coh\u00e9rence entre les \u00e9coles.<\/p>\n<p>\u00ab\u00a0<em><a href=\"https:\/\/stock.adobe.com\/images\/a-disabled-student-in-a-wheelchair-in-primary-school\/329490040?prev_url=detail&amp;asset_id=329490040\">Un \u00e9l\u00e8ve handicap\u00e9 en fauteuil roulant \u00e0 l&rsquo;\u00e9cole primaire,<\/a> \u00a9Adobe Stock\/andreysha74<\/em><\/p>\n","protected":false},"template":"","categories":[],"tags":[678,725,692,885,682,684,773],"class_list":["post-16069","policies","type-policies","status-publish","hentry","tag-enfants-et-jeunes","tag-groupes-a-faibles-revenus","tag-leducation","tag-liban","tag-moyen-orient-et-afrique-du-nord","tag-pays-a-revenu-intermediaire","tag-personnes-handicapees","policy-regions-middle-east-north-africa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Programme libanais d&#039;\u00e9ducation inclusive pour les enfants handicap\u00e9s<\/title>\n<meta name=\"description\" content=\"Le minist\u00e8re libanais de l&#039;\u00e9ducation et de l&#039;enseignement sup\u00e9rieur a lanc\u00e9 un programme pilote d&#039;\u00e9ducation inclusive (IE) en 2018.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sdg16.plus\/fr\/policies\/programme-libanais-deducation-inclusive-pour-les-enfants-handicapes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programme libanais d&#039;\u00e9ducation inclusive pour les enfants handicap\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Le minist\u00e8re libanais de l&#039;\u00e9ducation et de l&#039;enseignement sup\u00e9rieur a lanc\u00e9 un programme pilote d&#039;\u00e9ducation inclusive (IE) en 2018.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sdg16.plus\/fr\/policies\/programme-libanais-deducation-inclusive-pour-les-enfants-handicapes\/\" \/>\n<meta property=\"og:site_name\" content=\"Pathfinders\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-12T15:04:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/programme-libanais-deducation-inclusive-pour-les-enfants-handicapes\\\/\",\"url\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/programme-libanais-deducation-inclusive-pour-les-enfants-handicapes\\\/\",\"name\":\"Programme libanais d'\u00e9ducation inclusive pour les enfants handicap\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/#website\"},\"datePublished\":\"2023-04-21T14:45:45+00:00\",\"dateModified\":\"2024-12-12T15:04:55+00:00\",\"description\":\"Le minist\u00e8re libanais de l'\u00e9ducation et de l'enseignement sup\u00e9rieur a lanc\u00e9 un programme pilote d'\u00e9ducation inclusive (IE) en 2018.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/programme-libanais-deducation-inclusive-pour-les-enfants-handicapes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/programme-libanais-deducation-inclusive-pour-les-enfants-handicapes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/programme-libanais-deducation-inclusive-pour-les-enfants-handicapes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programme libanais d&#8217;\u00e9ducation inclusive pour les enfants handicap\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/\",\"name\":\"Pathfinders\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programme libanais d'\u00e9ducation inclusive pour les enfants handicap\u00e9s","description":"Le minist\u00e8re libanais de l'\u00e9ducation et de l'enseignement sup\u00e9rieur a lanc\u00e9 un programme pilote d'\u00e9ducation inclusive (IE) en 2018.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sdg16.plus\/fr\/policies\/programme-libanais-deducation-inclusive-pour-les-enfants-handicapes\/","og_locale":"fr_FR","og_type":"article","og_title":"Programme libanais d'\u00e9ducation inclusive pour les enfants handicap\u00e9s","og_description":"Le minist\u00e8re libanais de l'\u00e9ducation et de l'enseignement sup\u00e9rieur a lanc\u00e9 un programme pilote d'\u00e9ducation inclusive (IE) en 2018.","og_url":"https:\/\/www.sdg16.plus\/fr\/policies\/programme-libanais-deducation-inclusive-pour-les-enfants-handicapes\/","og_site_name":"Pathfinders","article_modified_time":"2024-12-12T15:04:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sdg16.plus\/fr\/policies\/programme-libanais-deducation-inclusive-pour-les-enfants-handicapes\/","url":"https:\/\/www.sdg16.plus\/fr\/policies\/programme-libanais-deducation-inclusive-pour-les-enfants-handicapes\/","name":"Programme libanais d'\u00e9ducation inclusive pour les enfants handicap\u00e9s","isPartOf":{"@id":"https:\/\/www.sdg16.plus\/fr\/#website"},"datePublished":"2023-04-21T14:45:45+00:00","dateModified":"2024-12-12T15:04:55+00:00","description":"Le minist\u00e8re libanais de l'\u00e9ducation et de l'enseignement sup\u00e9rieur a lanc\u00e9 un programme pilote d'\u00e9ducation inclusive (IE) en 2018.","breadcrumb":{"@id":"https:\/\/www.sdg16.plus\/fr\/policies\/programme-libanais-deducation-inclusive-pour-les-enfants-handicapes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sdg16.plus\/fr\/policies\/programme-libanais-deducation-inclusive-pour-les-enfants-handicapes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sdg16.plus\/fr\/policies\/programme-libanais-deducation-inclusive-pour-les-enfants-handicapes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sdg16.plus\/fr\/"},{"@type":"ListItem","position":2,"name":"Programme libanais d&#8217;\u00e9ducation inclusive pour les enfants handicap\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.sdg16.plus\/fr\/#website","url":"https:\/\/www.sdg16.plus\/fr\/","name":"Pathfinders","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sdg16.plus\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/policies\/16069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/policies"}],"about":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/types\/policies"}],"wp:attachment":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/media?parent=16069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/categories?post=16069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/tags?post=16069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}