{"id":16050,"date":"2023-10-09T03:16:43","date_gmt":"2023-10-09T03:16:43","guid":{"rendered":"https:\/\/www.sdg16.plus\/?post_type=policies&#038;p=16050"},"modified":"2024-12-06T21:24:18","modified_gmt":"2024-12-06T21:24:18","slug":"protection-sociale-tunisie","status":"publish","type":"policies","link":"https:\/\/www.sdg16.plus\/fr\/policies\/protection-sociale-tunisie\/","title":{"rendered":"Protection sociale : Tunisie"},"content":{"rendered":"<blockquote><p>Compar\u00e9 \u00e0 d&rsquo;autres pays de la r\u00e9gion arabe, le syst\u00e8me de protection sociale de la Tunisie est bien con\u00e7u. Il comprend des r\u00e9gimes contributifs pour une grande partie de la population active et des personnes \u00e0 leur charge, et des r\u00e9gimes non contributifs sous forme de subventions universelles, de transferts mon\u00e9taires cibl\u00e9s et d&rsquo;assurance maladie sociale pour les populations pauvres et vuln\u00e9rables.<sup><a href=\"#policy-reference-1\">1<\/a><\/sup><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p><\/blockquote>\n<p>Suite \u00e0 la r\u00e9volution de 2011 en Tunisie, le droit \u00e0 la protection sociale a \u00e9t\u00e9 renforc\u00e9 en vertu des principes de justice sociale. Le droit \u00e0 la couverture sociale est inscrit dans la Constitution depuis<sup><a href=\"#policy-reference-2\">20142<\/a>.<\/sup><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p>En 2019, le minist\u00e8re des affaires sociales a int\u00e9gr\u00e9 tous les programmes de protection sociale dans un seul programme, Amen Social. Le programme int\u00e8gre des programmes pr\u00e9existants, tels que le Programme national d&rsquo;aide aux familles n\u00e9cessiteuses (PNAFN), l&rsquo;Assistance m\u00e9dicale gratuite (AMGI) et le Programme d&rsquo;acc\u00e8s aux soins de sant\u00e9 \u00e0 tarif r\u00e9duit (AMGII), et les \u00e9largit pour inclure un plus grand nombre de personnes. Amen Social est une extension du concept de protection sociale et comprend des mesures allant au-del\u00e0 du revenu, telles que la sant\u00e9, l&rsquo;\u00e9ducation, l&rsquo;acc\u00e8s aux services publics et les conditions de vie.<sup><a href=\"#policy-reference-3\">3<\/a><\/sup> Amen Social repose sur deux piliers : l&rsquo;assistance sociale et l&rsquo;assurance sociale.  <a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<ol>\n<li>L&rsquo;<strong>aide sociale<\/strong> est fournie par l&rsquo;\u00c9tat \u00e0 des groupes cibl\u00e9s (personnes \u00e0 faible revenu, personnes handicap\u00e9es et personnes relevant du syst\u00e8me de soins de l&rsquo;\u00c9tat). Il comprend le PNAFN, qui fournit des transferts en esp\u00e8ces aux groupes vuln\u00e9rables et \u00e0 faibles revenus, ainsi que l&rsquo;AMGI et l&rsquo;AMGII, qui fournissent un acc\u00e8s subventionn\u00e9 ou gratuit aux soins de sant\u00e9 aux personnes qui ne sont pas couvertes par l&rsquo;assurance maladie, dans le but d&rsquo;atteindre la couverture sanitaire universelle.<sup><a href=\"#policy-reference-4\">4<\/a><\/sup><\/li>\n<li>L&rsquo;<strong>assurance sociale<\/strong> est fournie par l&rsquo;\u00c9tat gr\u00e2ce aux contributions des citoyens sous forme d&rsquo;imp\u00f4ts. Il comprend trois r\u00e9gimes : (1) la Caisse nationale de retraite et de pr\u00e9voyance sociale (CNRPS), (2) la Caisse nationale de s\u00e9curit\u00e9 sociale (CNSS) et (3) la Caisse nationale d&rsquo;assurance maladie (CNAM). La CNRPS et la CNSS offrent respectivement aux travailleurs du secteur public et du secteur priv\u00e9 une couverture en mati\u00e8re de retraite, d&rsquo;invalidit\u00e9, d&rsquo;accidents du travail, de d\u00e9c\u00e8s, de maternit\u00e9 et de paternit\u00e9 (bien qu&rsquo;il existe des prestations diff\u00e9rentes pour les diff\u00e9rentes cat\u00e9gories de travailleurs). La CNAM fournit une couverture sant\u00e9, notamment pour la maladie, les accidents et les maladies professionnelles, \u00e0 tous les travailleurs formellement employ\u00e9s (estim\u00e9s \u00e0 56 % du secteur priv\u00e9 en 2019).<sup><a href=\"#policy-reference-5\">5<\/a><\/sup><sup><a href=\"#policy-reference-6\">6<\/a><a href=\"#_ftn5\" name=\"_ftnref5\"><\/a><\/sup> Des subventions universelles existent pour les produits de base essentiels (g\u00e9n\u00e9ralement les denr\u00e9es alimentaires, le transport et le carburant).<\/li>\n<\/ol>\n<h2><b><hgroup class=\"section-group\"><svg class='section-group__icon' aria-hidden='true' slot='caret'><use xlink:href='#sprite-implementation'><\/use><\/svg><h2 class='section-group__heading'><\/b><b>Mise en \u0153uvre<\/b><b><\/h2><\/hgroup><\/b><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/h2>\n<p>Le syst\u00e8me de protection sociale tunisien a vu le jour dans les ann\u00e9es 1960 et a \u00e9t\u00e9 progressivement renforc\u00e9 au fil du temps pour devenir plus complet et s&rsquo;adapter aux nouvelles conditions sociales et de travail. Lors de la r\u00e9volution de 2011, il a \u00e9t\u00e9 \u00e0 nouveau reconnu que l&rsquo;assistance sociale excluait encore certains des m\u00e9nages tunisiens les plus vuln\u00e9rables, tels que les travailleurs informels, les populations rurales, les jeunes ch\u00f4meurs, les personnes handicap\u00e9es et les travailleurs migrants.<a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p>Le minist\u00e8re des affaires sociales supervise tous les programmes de protection sociale mentionn\u00e9s dans la section pr\u00e9c\u00e9dente (\u00e0 la fois l&rsquo;assistance sociale et l&rsquo;assurance sociale), bien que chaque programme soit g\u00e9r\u00e9 par un fonds de programme distinct.<a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p>L&rsquo;assurance sociale est g\u00e9r\u00e9e par la CNRPS pour les travailleurs du secteur public et par la CNSS pour les travailleurs du secteur priv\u00e9. Les cotisations m\u00e9dicales des travailleurs du secteur formel sont g\u00e9r\u00e9es par la CNAM.<a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p>L&rsquo;aide indirecte (et universelle) (sous forme de subventions) est transf\u00e9r\u00e9e par l&rsquo;interm\u00e9diaire de la Caisse g\u00e9n\u00e9rale de compensation (CGC), cr\u00e9\u00e9e en mai 1970 pour contr\u00f4ler les prix de certains produits alimentaires de base.<sup><a href=\"#policy-reference-7\">7<\/a><\/sup> Depuis 2013, les travailleurs sociaux du minist\u00e8re des affaires sociales recensent les b\u00e9n\u00e9ficiaires de l&rsquo;aide sociale dans le but de cr\u00e9er une base de donn\u00e9es exhaustive, d\u00e9sormais soutenue par l&rsquo;initiative du num\u00e9ro d&rsquo;identification sociale (NAS). L&rsquo;\u00e9ligibilit\u00e9 des b\u00e9n\u00e9ficiaires est confirm\u00e9e par un test de ressources de substitution, con\u00e7u pour r\u00e9duire les erreurs d&rsquo;inclusion (y compris les b\u00e9n\u00e9ficiaires non cibl\u00e9s) et d&rsquo;exclusion (excluant les b\u00e9n\u00e9ficiaires cibl\u00e9s).<sup><a href=\"#policy-reference-8\">8<\/a><\/sup><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<h2><b><hgroup class=\"section-group\"><svg class='section-group__icon' aria-hidden='true' slot='caret'><use xlink:href='#sprite-cost'><\/use><\/svg><h2 class='section-group__heading'><\/b><b>Co\u00fbt<\/b><b><\/h2><\/hgroup><\/b><\/h2>\n<p>Le minist\u00e8re tunisien des Finances a allou\u00e9 un milliard de dinars tunisiens (TND) (2,8 milliards USD), soit environ 5 % du budget 2022, \u00e0 la s\u00e9curit\u00e9 sociale.<sup><a href=\"#policy-reference-9\">9<\/a><\/sup><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p>En 2021, le co\u00fbt total du programme Amen a atteint 259 millions d&rsquo;USD, dont 229 millions d&rsquo;USD sous forme de transferts mon\u00e9taires.<sup><a href=\"#policy-reference-10\">10<\/a><\/sup> Dans le m\u00eame temps, 3 100 millions TND (environ 1,1 milliard USD au taux de change de 2021) ont \u00e9t\u00e9 allou\u00e9s \u00e0 des subventions : 2 200 millions TND (environ 800 millions USD) pour les produits de base (par exemple, la nourriture), 500 millions TND (180 millions USD) pour le transport et 400 millions TND (environ 150 millions USD) pour le carburant.<sup><a href=\"#policy-reference-11\">11<\/a><\/sup><a href=\"#_ftn10\" name=\"_ftnref10\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p>Les cotisations au titre de la CNRPS (pour les travailleurs du secteur public) s&rsquo;\u00e9l\u00e8vent \u00e0 23,7 % du salaire mensuel, dont 14,5 % sont vers\u00e9s par l&#8217;employeur et 9,2 % par l&#8217;employ\u00e9. Les cotisations \u00e0 la CNSS (travailleurs du secteur priv\u00e9) varient selon la cat\u00e9gorie de travailleurs. Pour les travailleurs non agricoles, les cotisations s&rsquo;\u00e9l\u00e8vent \u00e0 27,75 % du salaire, dont 16,57 % sont pay\u00e9s par l&#8217;employeur et 9,18 % par le salari\u00e9.<sup><a href=\"#policy-reference-12\">12<\/a><\/sup> Pour les travailleurs agricoles, les cotisations sont moins \u00e9lev\u00e9es.<a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<h2><b><hgroup class=\"section-group\"><svg class='section-group__icon' aria-hidden='true' slot='caret'><use xlink:href='#sprite-assessment'><\/use><\/svg><h2 class='section-group__heading'><\/b><b>L'\u00e9valuation<\/b><b><\/h2><\/hgroup><\/b><a href=\"#_ftn4\" name=\"_ftnref4\"><\/a><\/h2>\n<p>Le syst\u00e8me de protection sociale tunisien est souvent consid\u00e9r\u00e9 comme l&rsquo;un des plus performants de la r\u00e9gion arabe, car il int\u00e8gre des programmes compl\u00e9mentaires et s&rsquo;adresse \u00e0 l&rsquo;ensemble de la population tunisienne.<a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p>Sous l&rsquo;\u00e9gide d&rsquo;Amen Social, le PNAFN n&rsquo;a cess\u00e9 d&rsquo;augmenter l&rsquo;ampleur de l&rsquo;aide offerte et la couverture depuis sa cr\u00e9ation. Depuis 1987, il a augment\u00e9 plus rapidement que le salaire minimum (m\u00eame s&rsquo;il reste inf\u00e9rieur \u00e0 celui-ci). En 2021, 266 000 m\u00e9nages, soit 8 % de la population, ont b\u00e9n\u00e9fici\u00e9 de transferts mon\u00e9taires et de soins de sant\u00e9 gratuits. Les b\u00e9n\u00e9ficiaires des transferts mon\u00e9taires re\u00e7oivent 180 TND (64 USD) par mois, soit 45 % du salaire minimum, plus 30 TND par trimestre pour chaque enfant en \u00e2ge d&rsquo;\u00eatre scolaris\u00e9, afin d&rsquo;inciter les enfants \u00e0 rester \u00e0 l&rsquo;\u00e9cole.<sup><a href=\"#policy-reference-13\">13<\/a><\/sup><a href=\"#_ftn12\" name=\"_ftnref12\"><\/a> Dans le m\u00eame temps, 620 000 m\u00e9nages ont b\u00e9n\u00e9fici\u00e9 de soins de sant\u00e9 subventionn\u00e9s, ce qui porte le nombre total de b\u00e9n\u00e9ficiaires de soins de sant\u00e9 \u00e0 plus d&rsquo;un quart de la population.<sup><a href=\"#policy-reference-14\">14<\/a><\/sup><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p>75 % de la population cotisent \u00e0 un r\u00e9gime de retraite,<sup><a href=\"#policy-reference-15\">15<\/a><\/sup> tandis que la CNAM (assurance maladie pour les travailleurs formels) couvrait 8 064 733 personnes (environ 70 % de la population) en 2018.<sup><a href=\"#policy-reference-16\">16<\/a><\/sup><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p>Toutefois, les travailleurs du secteur priv\u00e9 (79 % de la population active, dont 56 % sont employ\u00e9s de mani\u00e8re formelle et 44 % de mani\u00e8re informelle<sup>)<a href=\"#policy-reference-17\">17<\/a><\/sup> et les travailleurs du secteur public (21 % de la population active) ne b\u00e9n\u00e9ficient pas des m\u00eames avantages. Les travailleurs du secteur priv\u00e9 b\u00e9n\u00e9ficient d&rsquo;une couverture de retraite moins favorable et d&rsquo;un cong\u00e9 de maternit\u00e9 plus court et moins bien r\u00e9mun\u00e9r\u00e9. Les \u00e9carts de r\u00e9mun\u00e9ration entre les hommes et les femmes et la faible participation des femmes au march\u00e9 du travail risquent de r\u00e9duire les cotisations des femmes \u00e0 l&rsquo;assurance sociale, et donc leurs pensions et prestations finales, et de nombreux versements de pensions restent inf\u00e9rieurs au salaire minimum. L&rsquo;assurance ch\u00f4mage ne couvre que les licenciements pour raisons technologiques ou \u00e9conomiques.<sup><a href=\"#policy-reference-18\">18<\/a><\/sup><a href=\"#_ftn17\" name=\"_ftnref17\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<p>Les r\u00e9gions pauvres sont moins bien \u00e9quip\u00e9es sur le plan m\u00e9dical et il existe donc une disparit\u00e9 dans les services de soins de sant\u00e9 fournis par les diff\u00e9rents types d&rsquo;assurance maladie et entre les r\u00e9gions pauvres et les r\u00e9gions riches.<sup><a href=\"#policy-reference-19\">19<\/a><\/sup><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref2\" name=\"_ftn2\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<h6>\u00ab\u00a0Homme dans le d\u00e9sert, \u00a9Adobe Stock\/Fotolibrary<\/h6>\n","protected":false},"template":"","categories":[],"tags":[819,678,725,682,684,773,676,881,703,707],"class_list":["post-16050","policies","type-policies","status-publish","hentry","tag-adultes-ages","tag-enfants-et-jeunes","tag-groupes-a-faibles-revenus","tag-moyen-orient-et-afrique-du-nord","tag-pays-a-revenu-intermediaire","tag-personnes-handicapees","tag-protection-sociale","tag-tunisie","tag-universel","tag-zones-rurales","policy-regions-middle-east-north-africa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Protection sociale : Tunisie - Pathfinders<\/title>\n<meta name=\"description\" content=\"Vers une protection sociale compl\u00e8te et inclusive en Tunisie (2014-en cours)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sdg16.plus\/fr\/policies\/protection-sociale-tunisie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protection sociale : Tunisie - Pathfinders\" \/>\n<meta property=\"og:description\" content=\"Vers une protection sociale compl\u00e8te et inclusive en Tunisie (2014-en cours)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sdg16.plus\/fr\/policies\/protection-sociale-tunisie\/\" \/>\n<meta property=\"og:site_name\" content=\"Pathfinders\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-06T21:24:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/protection-sociale-tunisie\\\/\",\"url\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/protection-sociale-tunisie\\\/\",\"name\":\"Protection sociale : Tunisie - Pathfinders\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/#website\"},\"datePublished\":\"2023-10-09T03:16:43+00:00\",\"dateModified\":\"2024-12-06T21:24:18+00:00\",\"description\":\"Vers une protection sociale compl\u00e8te et inclusive en Tunisie (2014-en cours)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/protection-sociale-tunisie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/protection-sociale-tunisie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/protection-sociale-tunisie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protection sociale : Tunisie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/\",\"name\":\"Pathfinders\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protection sociale : Tunisie - Pathfinders","description":"Vers une protection sociale compl\u00e8te et inclusive en Tunisie (2014-en cours)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sdg16.plus\/fr\/policies\/protection-sociale-tunisie\/","og_locale":"fr_FR","og_type":"article","og_title":"Protection sociale : Tunisie - Pathfinders","og_description":"Vers une protection sociale compl\u00e8te et inclusive en Tunisie (2014-en cours)","og_url":"https:\/\/www.sdg16.plus\/fr\/policies\/protection-sociale-tunisie\/","og_site_name":"Pathfinders","article_modified_time":"2024-12-06T21:24:18+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sdg16.plus\/fr\/policies\/protection-sociale-tunisie\/","url":"https:\/\/www.sdg16.plus\/fr\/policies\/protection-sociale-tunisie\/","name":"Protection sociale : Tunisie - Pathfinders","isPartOf":{"@id":"https:\/\/www.sdg16.plus\/fr\/#website"},"datePublished":"2023-10-09T03:16:43+00:00","dateModified":"2024-12-06T21:24:18+00:00","description":"Vers une protection sociale compl\u00e8te et inclusive en Tunisie (2014-en cours)","breadcrumb":{"@id":"https:\/\/www.sdg16.plus\/fr\/policies\/protection-sociale-tunisie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sdg16.plus\/fr\/policies\/protection-sociale-tunisie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sdg16.plus\/fr\/policies\/protection-sociale-tunisie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sdg16.plus\/fr\/"},{"@type":"ListItem","position":2,"name":"Protection sociale : Tunisie"}]},{"@type":"WebSite","@id":"https:\/\/www.sdg16.plus\/fr\/#website","url":"https:\/\/www.sdg16.plus\/fr\/","name":"Pathfinders","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sdg16.plus\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/policies\/16050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/policies"}],"about":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/types\/policies"}],"wp:attachment":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/media?parent=16050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/categories?post=16050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/tags?post=16050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}