{"id":16016,"date":"2023-05-17T20:02:43","date_gmt":"2023-05-17T20:02:43","guid":{"rendered":"https:\/\/www.sdg16.plus\/?post_type=policies&#038;p=16016"},"modified":"2024-12-06T19:58:21","modified_gmt":"2024-12-06T19:58:21","slug":"droits-fonciers-constitutionnels-pour-les-populations-autochtones-au-bresil","status":"publish","type":"policies","link":"https:\/\/www.sdg16.plus\/fr\/policies\/droits-fonciers-constitutionnels-pour-les-populations-autochtones-au-bresil\/","title":{"rendered":"Droits fonciers constitutionnels pour les populations autochtones au Br\u00e9sil"},"content":{"rendered":"<blockquote><p>Les droits des indig\u00e8nes sont reconnus au niveau f\u00e9d\u00e9ral par la constitution br\u00e9silienne adopt\u00e9e en 1988, les droits fonciers \u00e9tant explicitement prot\u00e9g\u00e9s et faisant l&rsquo;objet d&rsquo;une d\u00e9marcation (qui permet de d\u00e9limiter explicitement les terres et les propri\u00e9t\u00e9s et de d\u00e9signer les propri\u00e9taires) en vertu de l&rsquo;article 231. Avec une population indig\u00e8ne estim\u00e9e \u00e0 900 000 personnes et des terres indig\u00e8nes identifi\u00e9es repr\u00e9sentant une part importante de la masse terrestre du Br\u00e9sil. L&rsquo;article 231 et son mandat sont importants pour l&rsquo;autod\u00e9termination des peuples autochtones, les r\u00e9parations des si\u00e8cles de colonisation et la conservation de l&rsquo;environnement.<\/p><\/blockquote>\n<p>Les terres indig\u00e8nes identifi\u00e9es repr\u00e9sentent environ 13 % de la masse terrestre du Br\u00e9sil, ce qui \u00e9quivaut \u00e0 environ 106,7 millions d&rsquo;hectares, principalement en Amazonie, soit 462 terres diff\u00e9rentes reconnues.<sup><a href=\"#policy-reference-1\">1<\/a><\/sup> Au cours des ann\u00e9es 1970, un mouvement politique en faveur des droits des indig\u00e8nes a permis de mieux faire conna\u00eetre les questions relatives aux indig\u00e8nes et \u00e0 l&rsquo;environnement. Ce mouvement a \u00e9t\u00e9 organis\u00e9 par une coalition de d\u00e9fense des droits des indig\u00e8nes compos\u00e9e d&rsquo;organisations non gouvernementales nationales et internationales, d&rsquo;activistes et de politiciens de gauche. Des d\u00e9cennies de lutte pour la reconnaissance au niveau national, combin\u00e9es \u00e0 une campagne internationale de sensibilisation, ont abouti \u00e0 la Constitution de 1988, qui reconna\u00eet que les peuples indig\u00e8nes sont les premiers habitants du Br\u00e9sil.<\/p>\n<p>En particulier, l&rsquo;article 231 de la Constitution de 1988 reconna\u00eet que \u00ab\u00a0les peuples indig\u00e8nes sont les premiers et naturels propri\u00e9taires de la terre et garantit leur droit \u00e0 la terre\u00a0\u00bb.<sup><a href=\"#policy-reference-2\">2<\/a><\/sup> En vertu de la Constitution, le gouvernement f\u00e9d\u00e9ral est tenu de d\u00e9limiter les terres, ce qui constitue une garantie formelle, y compris un statut de protection, et de s&rsquo;efforcer de pr\u00e9server les terres indig\u00e8nes traditionnelles par le biais de proc\u00e9dures fonci\u00e8res l\u00e9gales formelles. Depuis 1988, le Br\u00e9sil a pris d&rsquo;autres engagements internationaux en faveur de la souverainet\u00e9 fonci\u00e8re des indig\u00e8nes, notamment en \u00e9tant l&rsquo;un des principaux partisans et signataires de la Convention n\u00b0 169 de l&rsquo;OIT sur les droits des peuples indig\u00e8nes et tribaux, adopt\u00e9e en 1989<sup><a href=\"#policy-reference-3\">3<\/a><\/sup> et la D\u00e9claration des Nations unies sur les droits des peuples autochtones (UNDRIP) en 2007.<sup><a href=\"#policy-reference-4\">4<\/a><\/sup><\/p>\n<h2><b><hgroup class=\"section-group\"><svg class='section-group__icon' aria-hidden='true' slot='caret'><use xlink:href='#sprite-implementation'><\/use><\/svg><h2 class='section-group__heading'><\/b><b>Mise en \u0153uvre<\/b><b><\/h2><\/hgroup><\/b><\/h2>\n<p>La d\u00e9marcation f\u00e9d\u00e9rale des terres indig\u00e8nes est plac\u00e9e sous la surveillance de la<em>FUNAI (Funda\u00e7\u00e3o Nacional dos Povos Ind\u00edgenas<\/em>), qui d\u00e9pend du minist\u00e8re de la justice. Le processus de d\u00e9limitation a \u00e9t\u00e9 mis \u00e0 jour \u00e0 plusieurs reprises : la derni\u00e8re mise \u00e0 jour a \u00e9t\u00e9 effectu\u00e9e par le d\u00e9cret 22 du 4 f\u00e9vrier 1991 et comprend sept \u00e9tapes : recherche, d\u00e9couverte, litiges, d\u00e9claration minist\u00e9rielle, d\u00e9limitation physique, homologation et enregistrement. Le d\u00e9cret 22 donne des indications non seulement sur la proc\u00e9dure d&rsquo;approbation, mais aussi sur l&rsquo;obligation de r\u00e9installer les occupants non autochtones (s&rsquo;il y en a).<sup><a href=\"#policy-reference-5\">5<\/a><\/sup> Une fois qu&rsquo;un territoire a re\u00e7u le statut de d\u00e9marcation, l&rsquo;acc\u00e8s aux terres par des personnes ext\u00e9rieures est limit\u00e9.<\/p>\n<p>Pendant la pr\u00e9sidence de Bolsonaro (2019-2022), la prise de d\u00e9cision concernant la d\u00e9marcation des terres indig\u00e8nes a \u00e9t\u00e9 transf\u00e9r\u00e9e au minist\u00e8re des droits de l&rsquo;homme, de la famille et de la femme, nouvellement cr\u00e9\u00e9, et au minist\u00e8re de l&rsquo;agriculture. Le d\u00e9cret a ensuite \u00e9t\u00e9 annul\u00e9 gr\u00e2ce \u00e0 la pression du Congr\u00e8s pour que l&rsquo;agence reste sous la juridiction du minist\u00e8re de la Justice en mai 2019.<sup><a href=\"#policy-reference-6\">6<\/a><\/sup> Le gouvernement nouvellement \u00e9lu (2023) pr\u00e9voit de reconstruire l&rsquo;agence et de relancer les processus de d\u00e9marcation en suspens, ainsi que d&rsquo;autres priorit\u00e9s pour r\u00e9pondre aux besoins des 900 000 peuples indig\u00e8nes du Br\u00e9sil.<sup><a href=\"#policy-reference-7\">7<\/a><\/sup><\/p>\n<h2><b><hgroup class=\"section-group\"><svg class='section-group__icon' aria-hidden='true' slot='caret'><use xlink:href='#sprite-cost'><\/use><\/svg><h2 class='section-group__heading'><\/b><b>Co\u00fbt<\/b><b><\/h2><\/hgroup><\/b><\/h2>\n<p>Les donn\u00e9es disponibles sur le budget de la FUNAI depuis 2018 indiquent un budget d&rsquo;environ 600 millions BRL (111 millions USD) par an, avec des d\u00e9penses r\u00e9parties entre les cat\u00e9gories suivantes (de la plus grande \u00e0 la plus petite) : administration g\u00e9n\u00e9rale, assistance aux populations indig\u00e8nes, charges sp\u00e9ciales, normalisation et inspection, protection et avantages des travailleurs, et \u00ab\u00a0autres\u00a0\u00bb. Toutefois, le budget n&rsquo;a pas \u00e9t\u00e9 enti\u00e8rement utilis\u00e9 au fil des ans.<sup><a href=\"#policy-reference-8\">8<\/a><\/sup> Les donn\u00e9es actuelles pour 2023 montrent que l&rsquo;agence dispose de 90 000 BRL (18 038,24 USD) pour les projets de d\u00e9marcation, ce qui \u00e9quivaut \u00e0 0,001 % du budget f\u00e9d\u00e9ral de 2023.<sup><a href=\"#policy-reference-9\">9<\/a><\/sup> Dans une interview accord\u00e9e \u00e0 InfoAmazonia, la nouvelle ministre de la FUNAI, Joenia Wapichana, demande que le Fonds pour l&rsquo;Amazonie et d&rsquo;autres sources de financement viennent renforcer le budget actuel consacr\u00e9 \u00e0 la d\u00e9marcation.<sup><a href=\"#policy-reference-10\">10<\/a><\/sup><\/p>\n<h2><b><hgroup class=\"section-group\"><svg class='section-group__icon' aria-hidden='true' slot='caret'><use xlink:href='#sprite-assessment'><\/use><\/svg><h2 class='section-group__heading'><\/b><b>L'\u00e9valuation<\/b><b><\/h2><\/hgroup><\/b><\/h2>\n<p>Le renforcement de la reconnaissance f\u00e9d\u00e9rale et de la d\u00e9marcation des terres indig\u00e8nes n&rsquo;apporte pas seulement des avantages culturels et spirituels, mais fait \u00e9galement progresser d&rsquo;autres droits pour les populations indig\u00e8nes &#8211; notamment l&rsquo;acc\u00e8s \u00e0 la nourriture, la s\u00e9curit\u00e9, la sant\u00e9, l&rsquo;\u00e9ducation, la justice &#8211; qui sont confront\u00e9es \u00e0 des in\u00e9galit\u00e9s sociales, environnementales, \u00e9conomiques et raciales disproportionn\u00e9es. Par exemple, une \u00e9tude environnementale r\u00e9alis\u00e9e en 2023 a r\u00e9v\u00e9l\u00e9 que le fait de conf\u00e9rer des droits fonciers formels aux terres autochtones &#8211; en d\u00e9limitant les territoires autochtones et en veillant \u00e0 ce qu&rsquo;ils aient un contr\u00f4le juridique total sur leurs terres &#8211; permet \u00e0 la fois de r\u00e9duire la d\u00e9forestation et d&rsquo;augmenter le reboisement dans la for\u00eat atlantique, une r\u00e9gion connue pour ses taux de d\u00e9forestation particuli\u00e8rement \u00e9lev\u00e9s. Par cons\u00e9quent, de nouvelles \u00e9tudes \u00e9tablissent un lien positif entre les droits et la souverainet\u00e9 des autochtones sur les terres traditionnelles et la pr\u00e9servation de la nature.<sup><a href=\"#policy-reference-11\">11<\/a><\/sup><\/p>\n<p>Bien que le processus de d\u00e9marcation ait progress\u00e9 depuis l&rsquo;entr\u00e9e en vigueur de la constitution en 1988 jusqu&rsquo;en 2016, 871 terres autochtones sont toujours en attente d&rsquo;une reconnaissance officielle.<sup><a href=\"#policy-reference-12\">12<\/a><\/sup> Les droits autochtones prot\u00e9g\u00e9s par la constitution ont \u00e9t\u00e9 \u00e9tendus et r\u00e9duits \u00e0 plusieurs reprises depuis lors, en fonction des administrations au pouvoir. Par exemple, les progr\u00e8s ont \u00e9t\u00e9 fortement ralentis lorsque l&rsquo;ancienne pr\u00e9sidente Dilma Rousseff a \u00e9t\u00e9 destitu\u00e9e et sous l&rsquo;administration de l&rsquo;ancien pr\u00e9sident Michel Temar (2016-18), une seule approbation de terres indig\u00e8nes a \u00e9t\u00e9 approuv\u00e9e, qui a fini par \u00eatre suspendue par une d\u00e9cision judiciaire. Sous l&rsquo;administration Bolsonaro (2019-2022), non seulement il n&rsquo;y a pas eu de nouvelles approbations fonci\u00e8res, mais un sentiment anti-indig\u00e8ne actif s&rsquo;est manifest\u00e9 dans les d\u00e9cisions politiques.<sup><a href=\"#policy-reference-13\">13<\/a><\/sup> (comme l&rsquo;exploitation mini\u00e8re ill\u00e9gale et l&rsquo;agro-industrie), ainsi que des violences li\u00e9es aux conflits fonciers et \u00e0 la d\u00e9forestation.<sup><a href=\"#policy-reference-14\">14<\/a><\/sup> Le pr\u00e9sident nouvellement \u00e9lu, Luiz In\u00e1cio Lula da Silva, fait d\u00e9sormais l&rsquo;objet de pressions pour qu&rsquo;il tienne ses <a href=\"https:\/\/lula.com.br\/o-compromisso-de-lula-com-os-povos-indigenas-e-a-foicada-de-bolsonaro-na-funai-e-no-meio-ambiente\/?__cf_chl_tk=p.yr8NLVxuMYWEQd5KfyZN_fu6LZRvgqJFpXCHT857U-1682987932-0-gaNycGzNC3s\">promesses de campagne, notamment<\/a>en s&rsquo;engageant \u00e0 assurer la souverainet\u00e9 des autochtones par le biais de la d\u00e9marcation des terres. Il s&rsquo;agit notamment d&rsquo;un appel \u00e0 l&rsquo;action lanc\u00e9 par les peuples autochtones et les d\u00e9fenseurs des droits pour d\u00e9limiter \u00ab\u00a013 nouveaux territoires autochtones qui ont franchi toutes les \u00e9tapes r\u00e9glementaires et ne n\u00e9cessitent rien d&rsquo;autre que l&rsquo;approbation du pr\u00e9sident pour \u00eatre officiels\u00a0\u00bb.<sup><a href=\"#policy-reference-15\">15<\/a> <\/sup>Le 28 avril 2023, le pr\u00e9sident Lula annonce la d\u00e9marcation de six territoires indig\u00e8nes, premi\u00e8re \u00e9tape de la r\u00e9alisation de ses promesses de campagne.<sup><a href=\"#policy-reference-16\">16<\/a><\/sup> Les critiques soulignent \u00e9galement la n\u00e9cessit\u00e9 de renforcer la mise en \u0153uvre de l&rsquo;article 231 dans la pratique et d&rsquo;utiliser des m\u00e9thodes de protestation telles que \u00ab\u00a0l&rsquo;occupation des terres et les manifestations sociales\u00a0\u00bb pour r\u00e9cup\u00e9rer les territoires traditionnels lorsque le processus officiel a \u00e9t\u00e9 lent \u00e0 se mettre en place, tant de la part des entreprises priv\u00e9es (principalement de l&rsquo;agro-industrie) que de l&rsquo;\u00c9tat.<sup><a href=\"#policy-reference-17\">17<\/a><\/sup><\/p>\n","protected":false},"template":"","categories":[321],"tags":[821,858,696,705,814,684,801,777],"class_list":["post-16016","policies","type-policies","status-publish","hentry","category-non-classifiee","tag-amerique-latine-et-caraibes","tag-bresil","tag-climat-et-environnement","tag-inegalites-spatiales","tag-justice-fr","tag-pays-a-revenu-intermediaire","tag-peuples-autochtones","tag-terre","policy-regions-latin-america-the-caribbean"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Droits fonciers constitutionnels pour les populations autochtones au Br\u00e9sil - Pathfinders<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sdg16.plus\/fr\/policies\/droits-fonciers-constitutionnels-pour-les-populations-autochtones-au-bresil\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Droits fonciers constitutionnels pour les populations autochtones au Br\u00e9sil - Pathfinders\" \/>\n<meta property=\"og:description\" content=\"Les droits des indig\u00e8nes sont reconnus au niveau f\u00e9d\u00e9ral par la constitution br\u00e9silienne adopt\u00e9e en 1988, les droits fonciers \u00e9tant explicitement prot\u00e9g\u00e9s et faisant l&rsquo;objet d&rsquo;une d\u00e9marcation (qui permet de d\u00e9limiter explicitement les terres et les propri\u00e9t\u00e9s et de d\u00e9signer les propri\u00e9taires) en vertu de l&rsquo;article 231. Avec une population indig\u00e8ne estim\u00e9e \u00e0 900 000\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sdg16.plus\/fr\/policies\/droits-fonciers-constitutionnels-pour-les-populations-autochtones-au-bresil\/\" \/>\n<meta property=\"og:site_name\" content=\"Pathfinders\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-06T19:58:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/droits-fonciers-constitutionnels-pour-les-populations-autochtones-au-bresil\\\/\",\"url\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/droits-fonciers-constitutionnels-pour-les-populations-autochtones-au-bresil\\\/\",\"name\":\"Droits fonciers constitutionnels pour les populations autochtones au Br\u00e9sil - Pathfinders\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/#website\"},\"datePublished\":\"2023-05-17T20:02:43+00:00\",\"dateModified\":\"2024-12-06T19:58:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/droits-fonciers-constitutionnels-pour-les-populations-autochtones-au-bresil\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/droits-fonciers-constitutionnels-pour-les-populations-autochtones-au-bresil\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/policies\\\/droits-fonciers-constitutionnels-pour-les-populations-autochtones-au-bresil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Droits fonciers constitutionnels pour les populations autochtones au Br\u00e9sil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/\",\"name\":\"Pathfinders\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sdg16.plus\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Droits fonciers constitutionnels pour les populations autochtones au Br\u00e9sil - Pathfinders","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sdg16.plus\/fr\/policies\/droits-fonciers-constitutionnels-pour-les-populations-autochtones-au-bresil\/","og_locale":"fr_FR","og_type":"article","og_title":"Droits fonciers constitutionnels pour les populations autochtones au Br\u00e9sil - Pathfinders","og_description":"Les droits des indig\u00e8nes sont reconnus au niveau f\u00e9d\u00e9ral par la constitution br\u00e9silienne adopt\u00e9e en 1988, les droits fonciers \u00e9tant explicitement prot\u00e9g\u00e9s et faisant l&rsquo;objet d&rsquo;une d\u00e9marcation (qui permet de d\u00e9limiter explicitement les terres et les propri\u00e9t\u00e9s et de d\u00e9signer les propri\u00e9taires) en vertu de l&rsquo;article 231. Avec une population indig\u00e8ne estim\u00e9e \u00e0 900 000","og_url":"https:\/\/www.sdg16.plus\/fr\/policies\/droits-fonciers-constitutionnels-pour-les-populations-autochtones-au-bresil\/","og_site_name":"Pathfinders","article_modified_time":"2024-12-06T19:58:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sdg16.plus\/fr\/policies\/droits-fonciers-constitutionnels-pour-les-populations-autochtones-au-bresil\/","url":"https:\/\/www.sdg16.plus\/fr\/policies\/droits-fonciers-constitutionnels-pour-les-populations-autochtones-au-bresil\/","name":"Droits fonciers constitutionnels pour les populations autochtones au Br\u00e9sil - Pathfinders","isPartOf":{"@id":"https:\/\/www.sdg16.plus\/fr\/#website"},"datePublished":"2023-05-17T20:02:43+00:00","dateModified":"2024-12-06T19:58:21+00:00","breadcrumb":{"@id":"https:\/\/www.sdg16.plus\/fr\/policies\/droits-fonciers-constitutionnels-pour-les-populations-autochtones-au-bresil\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sdg16.plus\/fr\/policies\/droits-fonciers-constitutionnels-pour-les-populations-autochtones-au-bresil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sdg16.plus\/fr\/policies\/droits-fonciers-constitutionnels-pour-les-populations-autochtones-au-bresil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sdg16.plus\/fr\/"},{"@type":"ListItem","position":2,"name":"Droits fonciers constitutionnels pour les populations autochtones au Br\u00e9sil"}]},{"@type":"WebSite","@id":"https:\/\/www.sdg16.plus\/fr\/#website","url":"https:\/\/www.sdg16.plus\/fr\/","name":"Pathfinders","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sdg16.plus\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/policies\/16016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/policies"}],"about":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/types\/policies"}],"wp:attachment":[{"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/media?parent=16016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/categories?post=16016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sdg16.plus\/fr\/wp-json\/wp\/v2\/tags?post=16016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}