{"id":16135,"date":"2023-04-21T14:45:45","date_gmt":"2023-04-21T14:45:45","guid":{"rendered":"https:\/\/www.sdg16.plus\/?post_type=policies&#038;p=16135"},"modified":"2024-12-13T15:59:34","modified_gmt":"2024-12-13T15:59:34","slug":"proporcionar-un-seguro-de-desempleo-a-los-trabajadores-nacionales-y-extranjeros-y-a-los-que-buscan-trabajo-por-primera-vez-en-bahrein","status":"publish","type":"policies","link":"https:\/\/www.sdg16.plus\/es\/policies\/proporcionar-un-seguro-de-desempleo-a-los-trabajadores-nacionales-y-extranjeros-y-a-los-que-buscan-trabajo-por-primera-vez-en-bahrein\/","title":{"rendered":"Proporcionar un seguro de desempleo a los trabajadores nacionales y extranjeros, y a los que buscan trabajo por primera vez en Bahrein."},"content":{"rendered":"<blockquote><p>En 2006, Bahr\u00e9in adopt\u00f3 su primer r\u00e9gimen de seguro de desempleo, que ofrece protecci\u00f3n por desempleo a los trabajadores nacionales y extranjeros de los sectores p\u00fablico y privado, y a los j\u00f3venes desempleados que buscan trabajo por primera vez. El programa ha sido aclamado por reducir la desigualdad en el acceso a la protecci\u00f3n por desempleo entre nacionales y trabajadores inmigrantes (que constitu\u00edan el 63% de la mano de obra en 2020<sup><a href=\"\/#policy-reference-1\">1<\/a><\/sup> y entre los j\u00f3venes desempleados (que constitu\u00edan el 7% de la mano de obra juvenil en 2021).<\/p><\/blockquote>\n<p>El seguro de desempleo ofrece dos tipos de reembolsos: una \u00abprestaci\u00f3n compensatoria\u00bb a los nacionales y trabajadores extranjeros que pierden su empleo, y una \u00abprestaci\u00f3n de ayuda al desempleo\u00bb a los bahrein\u00edes que buscan trabajo por primera vez. La prestaci\u00f3n compensatoria es especialmente novedosa porque cubre a los trabajadores inmigrantes, que constituyen el 63% de la mano de obra bahrein\u00ed y antes no estaban asegurados por desempleo. La prestaci\u00f3n de ayuda al desempleo tambi\u00e9n es \u00fanica en el sentido de que proporciona una ayuda monetaria para combatir el desempleo juvenil.<\/p>\n<p>La prestaci\u00f3n compensatoria proporciona al trabajador nacional\/extranjero un pago mensual equivalente al 60% de su salario anterior, con un pago mensual m\u00ednimo de 200 BD (530 USD) y un m\u00e1ximo de 1.000 BD (2.650 USD), durante un periodo m\u00e1ximo de nueve meses. Los trabajadores pueden solicitar la prestaci\u00f3n en varias ocasiones, siempre que hayan trabajado entre cada solicitud. Para que el trabajador pueda beneficiarse de la indemnizaci\u00f3n, debe estar dado de alta en la Organizaci\u00f3n General de la Seguridad Social (OGS) durante al menos 12 meses, no haber sido despedido por cuestiones disciplinarias, no haber dimitido voluntariamente y tener residencia legal (para los expatriados).<sup><a href=\"#policy-reference-2\">2<\/a><\/sup><\/p>\n<p>La prestaci\u00f3n de ayuda al desempleo, da derecho a los desempleados bahrein\u00edes que buscan trabajo por primera vez (o a los que llevan menos de un a\u00f1o trabajando y, por tanto, no tendr\u00edan derecho a la prestaci\u00f3n compensatoria) a un estipendio mensual de 200 BD (530 USD) si tienen un t\u00edtulo, o de 150 BD (398 USD) si no lo tienen. Los estipendios se pagan durante un m\u00e1ximo de seis meses en cualquier periodo de 12 meses. Los beneficiarios deben realizar programas de formaci\u00f3n impartidos por el Ministerio de Trabajo (MdT) para tener derecho a la prestaci\u00f3n. A continuaci\u00f3n, los programas de formaci\u00f3n se emparejan con sugerencias de b\u00fasqueda de empleo y el Ministerio de Trabajo empareja a los j\u00f3venes con las oportunidades de empleo. Los beneficiarios pierden el acceso a la prestaci\u00f3n de ayuda por desempleo si rechazan la segunda oferta de trabajo proporcionada por el Ministerio de Trabajo sin una justificaci\u00f3n racional, es decir, si se est\u00e1 sobrecualificado para el trabajo o se tiene que recorrer una gran distancia hasta el lugar de trabajo.<sup><a href=\"#policy-reference-3\">3<\/a><\/sup><\/p>\n<h2><b><hgroup class=\"section-group\"><svg class='section-group__icon' aria-hidden='true' slot='caret'><use xlink:href='#sprite-implementation'><\/use><\/svg><h2 class='section-group__heading'><\/b><b>Aplicaci\u00f3n<\/b><b><\/h2><\/hgroup><\/b><\/h2>\n<p>Bahr\u00e9in present\u00f3 por primera vez el seguro de desempleo en 2001, en el marco de su Programa de Trabajo Decente.<sup><a href=\"#policy-reference-4\">4<\/a><\/sup> En 2006, con el apoyo de la Organizaci\u00f3n Internacional del Trabajo (OIT) y utilizando los resultados de la encuesta de poblaci\u00f3n activa de 2004 y un estudio actuarial,<sup><a href=\"#policy-reference-5\">5<\/a><\/sup> se modific\u00f3 la Ley del Trabajo y se introdujo el seguro de desempleo mediante el decreto legislativo n\u00famero 78 de la Ley del Trabajo.<sup><a href=\"#policy-reference-6\">6<\/a><\/sup><\/p>\n<p>Los reg\u00edmenes de seguro de desempleo son gestionados por el Ministerio de Trabajo y la Organizaci\u00f3n General de la Seguridad Social. El Ministerio de Trabajo es responsable de la aceptaci\u00f3n de las solicitudes, la formaci\u00f3n de los solicitantes y el emparejamiento de los solicitantes de empleo con las vacantes, mientras que la GOSI es responsable de recaudar y desembolsar los fondos. Se cre\u00f3 un comit\u00e9 de coordinaci\u00f3n, formado por representantes del Ministerio de Trabajo y de la GOSI, para aplicar el r\u00e9gimen de seguro de desempleo y garantizar una coordinaci\u00f3n eficaz entre los organismos.<sup><a href=\"#policy-reference-7\">7<\/a><\/sup><\/p>\n<h2><b><hgroup class=\"section-group\"><svg class='section-group__icon' aria-hidden='true' slot='caret'><use xlink:href='#sprite-cost'><\/use><\/svg><h2 class='section-group__heading'><\/b><b>Coste<\/b><b><\/h2><\/hgroup><\/b><\/h2>\n<p>Los reg\u00edmenes combinados de seguro de desempleo se financian mediante una cotizaci\u00f3n del 1% sobre los salarios de los trabajadores, que es igualada por separado por el empresario y por el Gobierno de Bahrein, lo que supone una cotizaci\u00f3n total del 3%.<sup><a href=\"#policy-reference-8\">8<\/a><\/sup><\/p>\n<p>Para 2020, el fondo del seguro de desempleo recibi\u00f3 78,6 millones de BD (208,3 millones de USD) en cotizaciones, y pag\u00f3 26,8 millones de BD (71 millones de USD) en prestaciones. Los activos netos del fondo alcanzaron los 508,7 millones de BD (1.300 millones de USD) el 31 de diciembre de 2020.<sup><a href=\"#policy-reference-9\">9<\/a><\/sup><\/p>\n<h2><b><hgroup class=\"section-group\"><svg class='section-group__icon' aria-hidden='true' slot='caret'><use xlink:href='#sprite-assessment'><\/use><\/svg><h2 class='section-group__heading'><\/b><b>Evaluaci\u00f3n<\/b><b><\/h2><\/hgroup><\/b><\/h2>\n<p>La OIT elogi\u00f3 el seguro de desempleo de Bahr\u00e9in como sistema pionero en Oriente Medio y la Regi\u00f3n \u00c1rabe.<sup><a href=\"#policy-reference-10\">10<\/a><\/sup> Ha conseguido proteger a los trabajadores de las crisis econ\u00f3micas y reducir las desigualdades en el acceso a la protecci\u00f3n por desempleo, sobre todo para los trabajadores inmigrantes, al incluirlos en el r\u00e9gimen de protecci\u00f3n.<sup><a href=\"#policy-reference-11\">11<\/a><\/sup><\/p>\n<p>A finales de 2022, hab\u00eda 29.000 beneficiarios registrados del seguro de desempleo, y 10.000 beneficiarios de programas de formaci\u00f3n.<sup><a href=\"#policy-reference-12\">12<\/a><\/sup> Con un 5,5<sup><a href=\"#policy-reference-13\">13<\/a><\/sup> de desempleo en Bahr\u00e9in, el seguro de desempleo estar\u00eda cubriendo al 36% de los desempleados. El seguro de desempleo de Bahrein desempe\u00f1\u00f3 un papel importante en la protecci\u00f3n de los trabajadores frente a las grandes p\u00e9rdidas de empleo en medio de la recesi\u00f3n econ\u00f3mica y las restricciones de movimiento durante la COVID-19. Entre 2019 y 2021, hubo 41.897 beneficiarios del seguro de desempleo y 24.344 j\u00f3venes obtuvieron un empleo.<sup> <a href=\"#policy-reference-14\">14<\/a><\/sup><\/p>\n<p>La prestaci\u00f3n de ayuda al desempleo no ha contribuido a reducir el desempleo juvenil como se esperaba, ya que Bahr\u00e9in ha experimentado (en consonancia con la regi\u00f3n \u00e1rabe en general) un crecimiento masivo de la poblaci\u00f3n y una creaci\u00f3n de empleo limitada. Sin embargo, el desempleo juvenil en Bahr\u00e9in es relativamente bajo (siete por ciento en 2021) en comparaci\u00f3n con la regi\u00f3n \u00e1rabe (26 por ciento en 2021), lo que probablemente pueda atribuirse en parte a la prestaci\u00f3n de ayuda al desempleo, en particular a las condiciones de formaci\u00f3n y adecuaci\u00f3n al puesto de trabajo que ofrece el Ministerio de Trabajo.<sup><a href=\"#policy-reference-15\">15<\/a><\/sup><\/p>\n<p>No todos los bahrein\u00edes est\u00e1n contentos con que el seguro de desempleo cubra tanto a los trabajadores nacionales como a los extranjeros. Durante la COVID-19, el gobierno se vio obligado a borrar una publicaci\u00f3n de Twitter que detallaba sus prestaciones de desempleo para trabajadores extranjeros, en medio de una reacci\u00f3n xen\u00f3foba. Esto no tuvo un impacto material en la pol\u00edtica, pero ha exigido al Gobierno que d\u00e9 prioridad visiblemente a las prestaciones de los ciudadanos bahrein\u00edes en los cargos p\u00fablicos.<sup><a href=\"#policy-reference-16\">16<\/a><\/sup><\/p>\n","protected":false},"template":"","categories":[1],"tags":[920,733,758,826,745,679,752,753,743,770,771],"class_list":["post-16135","policies","type-policies","status-publish","hentry","category-uncategorized","tag-bahrein-es","tag-grupos-de-bajos-ingresos","tag-infancia-y-juventud","tag-migrantes-y-refugiados","tag-oriente-medio-y-norte-de-africa","tag-pais-de-renta-alta","tag-proteccion-social","tag-redistribucion","tag-renta-y-patrimonio","tag-trabajo","tag-universal-es","policy-regions-middle-east-north-africa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seguro de desempleo en Bahr\u00e9in | Portal de Soluciones para la Desigualdad<\/title>\n<meta name=\"description\" content=\"Prestaci\u00f3n del seguro de desempleo a los trabajadores nacionales y extranjeros y a los bahrein\u00edes que buscan trabajo por primera vez (2006-actualidad)l\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sdg16.plus\/es\/policies\/proporcionar-un-seguro-de-desempleo-a-los-trabajadores-nacionales-y-extranjeros-y-a-los-que-buscan-trabajo-por-primera-vez-en-bahrein\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seguro de desempleo en Bahr\u00e9in | Portal de Soluciones para la Desigualdad\" \/>\n<meta property=\"og:description\" content=\"Prestaci\u00f3n del seguro de desempleo a los trabajadores nacionales y extranjeros y a los bahrein\u00edes que buscan trabajo por primera vez (2006-actualidad)l\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sdg16.plus\/es\/policies\/proporcionar-un-seguro-de-desempleo-a-los-trabajadores-nacionales-y-extranjeros-y-a-los-que-buscan-trabajo-por-primera-vez-en-bahrein\/\" \/>\n<meta property=\"og:site_name\" content=\"Pathfinders\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-13T15:59:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/policies\\\/proporcionar-un-seguro-de-desempleo-a-los-trabajadores-nacionales-y-extranjeros-y-a-los-que-buscan-trabajo-por-primera-vez-en-bahrein\\\/\",\"url\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/policies\\\/proporcionar-un-seguro-de-desempleo-a-los-trabajadores-nacionales-y-extranjeros-y-a-los-que-buscan-trabajo-por-primera-vez-en-bahrein\\\/\",\"name\":\"Seguro de desempleo en Bahr\u00e9in | Portal de Soluciones para la Desigualdad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/#website\"},\"datePublished\":\"2023-04-21T14:45:45+00:00\",\"dateModified\":\"2024-12-13T15:59:34+00:00\",\"description\":\"Prestaci\u00f3n del seguro de desempleo a los trabajadores nacionales y extranjeros y a los bahrein\u00edes que buscan trabajo por primera vez (2006-actualidad)l\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/policies\\\/proporcionar-un-seguro-de-desempleo-a-los-trabajadores-nacionales-y-extranjeros-y-a-los-que-buscan-trabajo-por-primera-vez-en-bahrein\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/policies\\\/proporcionar-un-seguro-de-desempleo-a-los-trabajadores-nacionales-y-extranjeros-y-a-los-que-buscan-trabajo-por-primera-vez-en-bahrein\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/policies\\\/proporcionar-un-seguro-de-desempleo-a-los-trabajadores-nacionales-y-extranjeros-y-a-los-que-buscan-trabajo-por-primera-vez-en-bahrein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proporcionar un seguro de desempleo a los trabajadores nacionales y extranjeros, y a los que buscan trabajo por primera vez en Bahrein.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/\",\"name\":\"Pathfinders\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seguro de desempleo en Bahr\u00e9in | Portal de Soluciones para la Desigualdad","description":"Prestaci\u00f3n del seguro de desempleo a los trabajadores nacionales y extranjeros y a los bahrein\u00edes que buscan trabajo por primera vez (2006-actualidad)l","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sdg16.plus\/es\/policies\/proporcionar-un-seguro-de-desempleo-a-los-trabajadores-nacionales-y-extranjeros-y-a-los-que-buscan-trabajo-por-primera-vez-en-bahrein\/","og_locale":"es_ES","og_type":"article","og_title":"Seguro de desempleo en Bahr\u00e9in | Portal de Soluciones para la Desigualdad","og_description":"Prestaci\u00f3n del seguro de desempleo a los trabajadores nacionales y extranjeros y a los bahrein\u00edes que buscan trabajo por primera vez (2006-actualidad)l","og_url":"https:\/\/www.sdg16.plus\/es\/policies\/proporcionar-un-seguro-de-desempleo-a-los-trabajadores-nacionales-y-extranjeros-y-a-los-que-buscan-trabajo-por-primera-vez-en-bahrein\/","og_site_name":"Pathfinders","article_modified_time":"2024-12-13T15:59:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sdg16.plus\/es\/policies\/proporcionar-un-seguro-de-desempleo-a-los-trabajadores-nacionales-y-extranjeros-y-a-los-que-buscan-trabajo-por-primera-vez-en-bahrein\/","url":"https:\/\/www.sdg16.plus\/es\/policies\/proporcionar-un-seguro-de-desempleo-a-los-trabajadores-nacionales-y-extranjeros-y-a-los-que-buscan-trabajo-por-primera-vez-en-bahrein\/","name":"Seguro de desempleo en Bahr\u00e9in | Portal de Soluciones para la Desigualdad","isPartOf":{"@id":"https:\/\/www.sdg16.plus\/es\/#website"},"datePublished":"2023-04-21T14:45:45+00:00","dateModified":"2024-12-13T15:59:34+00:00","description":"Prestaci\u00f3n del seguro de desempleo a los trabajadores nacionales y extranjeros y a los bahrein\u00edes que buscan trabajo por primera vez (2006-actualidad)l","breadcrumb":{"@id":"https:\/\/www.sdg16.plus\/es\/policies\/proporcionar-un-seguro-de-desempleo-a-los-trabajadores-nacionales-y-extranjeros-y-a-los-que-buscan-trabajo-por-primera-vez-en-bahrein\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sdg16.plus\/es\/policies\/proporcionar-un-seguro-de-desempleo-a-los-trabajadores-nacionales-y-extranjeros-y-a-los-que-buscan-trabajo-por-primera-vez-en-bahrein\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sdg16.plus\/es\/policies\/proporcionar-un-seguro-de-desempleo-a-los-trabajadores-nacionales-y-extranjeros-y-a-los-que-buscan-trabajo-por-primera-vez-en-bahrein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sdg16.plus\/es\/"},{"@type":"ListItem","position":2,"name":"Proporcionar un seguro de desempleo a los trabajadores nacionales y extranjeros, y a los que buscan trabajo por primera vez en Bahrein."}]},{"@type":"WebSite","@id":"https:\/\/www.sdg16.plus\/es\/#website","url":"https:\/\/www.sdg16.plus\/es\/","name":"Pathfinders","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sdg16.plus\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.sdg16.plus\/es\/wp-json\/wp\/v2\/policies\/16135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sdg16.plus\/es\/wp-json\/wp\/v2\/policies"}],"about":[{"href":"https:\/\/www.sdg16.plus\/es\/wp-json\/wp\/v2\/types\/policies"}],"wp:attachment":[{"href":"https:\/\/www.sdg16.plus\/es\/wp-json\/wp\/v2\/media?parent=16135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sdg16.plus\/es\/wp-json\/wp\/v2\/categories?post=16135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sdg16.plus\/es\/wp-json\/wp\/v2\/tags?post=16135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}