{"id":16088,"date":"2023-10-09T03:38:18","date_gmt":"2023-10-09T03:38:18","guid":{"rendered":"https:\/\/www.sdg16.plus\/?post_type=policies&#038;p=16088"},"modified":"2024-12-13T14:50:10","modified_gmt":"2024-12-13T14:50:10","slug":"apoyar-el-desempleo-mediante-la-startup-act-tunez","status":"publish","type":"policies","link":"https:\/\/www.sdg16.plus\/es\/policies\/apoyar-el-desempleo-mediante-la-startup-act-tunez\/","title":{"rendered":"Apoyar el desempleo mediante la Startup Act: T\u00fanez"},"content":{"rendered":"<blockquote><p>En 2018, T\u00fanez puso en marcha la pol\u00edtica Startup Tunisia a trav\u00e9s del portal en l\u00ednea \u00abStartup Tunisia\u00bb, que proporciona acceso a financiaci\u00f3n, asesoramiento empresarial y oportunidades de creaci\u00f3n de redes para apoyar la diversificaci\u00f3n econ\u00f3mica y el crecimiento inclusivo, y para hacer frente al creciente desempleo juvenil y femenino. Startup T\u00fanez est\u00e1 regulada por la Ley de Startups, que se elabor\u00f3 mediante un proceso consultivo entre el gobierno y el sector privado para facilitar la creaci\u00f3n, financiaci\u00f3n y crecimiento de las startups.<\/p><\/blockquote>\n<p>En 2011, la tasa de desempleo en T\u00fanez alcanz\u00f3 el 18%.<sup><a href=\"#policy-reference-1\">1<\/a><\/sup> Un 27% de mujeres y un 42% de j\u00f3venes desempleados. El elevado desempleo fue uno de los catalizadores de la revoluci\u00f3n tunecina (2010-11) y constituy\u00f3 un punto clave del programa del gobierno democr\u00e1tico para restablecer la justicia social. El gobierno posterior a 2014 consider\u00f3 el esp\u00edritu empresarial y la creaci\u00f3n de peque\u00f1as y medianas empresas (PYME) como una v\u00eda para crear puestos de trabajo, aliviar el elevado desempleo, diversificar la econom\u00eda e impulsar el crecimiento econ\u00f3mico. Sin embargo, el acceso a las licencias empresariales y a la financiaci\u00f3n inicial estaba monopolizado en gran medida por quienes ten\u00edan conexiones con el gobierno. Por ello, muchos j\u00f3venes se enfrentaron a obst\u00e1culos para crear sus propias empresas.<sup><a href=\"#policy-reference-2\">2<\/a><\/sup><\/p>\n<p>La Ley de Puesta en Marcha fue ratificada en 2018. Define las startups como nuevas empresas que tienen menos de ocho a\u00f1os, menos de 100 empleados y m\u00e1s de dos tercios de sus accionistas son fundadores.<\/p>\n<p>La Ley fomenta el esp\u00edritu empresarial al permitir a los trabajadores del sector privado y p\u00fablico tomarse un a\u00f1o (ampliable a dos) de permiso sin sueldo para crear una empresa, garantizando al mismo tiempo la protecci\u00f3n de su empleo actual. Cualquier persona puede solicitar una startup. La Ley estipula que, una vez reconocidas, las nuevas startups reciben fondos para cubrir el coste de las patentes y financiar los salarios de hasta tres fundadores [1.496 dinares tunecinos (TND) al mes de media, 493 d\u00f3lares estadounidenses (USD)] durante el primer a\u00f1o de operaciones. La Ley tambi\u00e9n estipula que las empresas de nueva creaci\u00f3n est\u00e1n exentas de impuestos sobre el capital, la importaci\u00f3n y las aduanas, y permite un acceso preferente a las divisas (normalmente limitado) para que las nuevas empresas puedan acceder a los mercados internacionales.<\/p>\n<p>Startup Tunisia ofrece a las startups reconocidas dos servicios principales: Startup Ecosystem y Startup Invest. <strong>Startup Ecosystem <\/strong>es un marco de apoyo que se centra en la conexi\u00f3n y la promoci\u00f3n.<sup><a href=\"#policy-reference-3\">3<\/a><\/sup> Proporciona fondos (que oscilan entre 30.000 y 200.000 TND, o 9.855 y 65.703 USD),<sup><a href=\"#policy-reference-4\">4<\/a><\/sup> formaci\u00f3n y exposici\u00f3n internacional a las startups tunecinas,<sup><a href=\"#policy-reference-5\">5<\/a><\/sup> y apoya a las startups en diferentes etapas, desde la concepci\u00f3n, la incubaci\u00f3n y la aceleraci\u00f3n hasta el crecimiento. <strong>Startup Invest<\/strong> es un marco de inversi\u00f3n que pretende crear un ecosistema de capital riesgo<sup><a href=\"#policy-reference-6\">6<\/a><\/sup><a href=\"#_ftn6\" name=\"_ftnref6\"><\/a> (VC) con alto valor a\u00f1adido para las startups. Apoya el acceso de los empresarios a la financiaci\u00f3n reuniendo los fondos de los inversores y proporcionando garant\u00edas de inversi\u00f3n. El mayor acceso a la financiaci\u00f3n tambi\u00e9n se ve respaldado por el asesoramiento financiero a trav\u00e9s de programas de educaci\u00f3n y formaci\u00f3n impartidos por expertos nacionales e internacionales.<\/p>\n<p>Startup T\u00fanez tiene tres grandes objetivos que deben alcanzarse para 2024: identificar y apoyar a 1.000 empresas de nueva creaci\u00f3n; crear 10.000 nuevos puestos de trabajo; y apoyar a las empresas de nueva creaci\u00f3n con un volumen de negocio acumulado de 1.000 millones de TND.<\/p>\n<h2><b><hgroup class=\"section-group\"><svg class='section-group__icon' aria-hidden='true' slot='caret'><use xlink:href='#sprite-aplicaci\u00f3n'><\/use><\/svg><h2 class='section-group__heading'><\/b><b>Aplicaci\u00f3n<\/b><b><\/h2><\/hgroup><\/b><\/h2>\n<p>Para superar algunas de las barreras reconocidas y facilitar el entorno empresarial, en 2016 se cre\u00f3 un grupo de trabajo sobre startups formado por 70 inversores, empresarios, banqueros y el Ministro de Comunicaciones. El grupo de trabajo sobre startups se encarg\u00f3 de reformar el entorno empresarial, con especial atenci\u00f3n a los j\u00f3venes, las mujeres y el sector tecnol\u00f3gico. La Ley de Puesta en Marcha fue uno de los primeros resultados del grupo de trabajo, y se defendi\u00f3 a trav\u00e9s de las redes sociales para aumentar su tracci\u00f3n, sobre todo entre los j\u00f3venes.<\/p>\n<p>Tambi\u00e9n se cre\u00f3 una academia parlamentaria para que los parlamentarios conocieran mejor la Startup Act y la necesidad de reformar el entorno empresarial.  <sup><a href=\"#policy-reference-7\">7<\/a><\/sup><\/p>\n<p>La Startup Act se aplica a trav\u00e9s de Startup T\u00fanez,<sup><a href=\"#policy-reference-8\">8<\/a><\/sup> una plataforma en l\u00ednea creada por el Ministerio de Tecnolog\u00edas de la Comunicaci\u00f3n en 2018.<sup><a href=\"#policy-reference-9\">9<\/a><\/sup> La plataforma permite a los emprendedores solicitar la etiqueta de startup. Una vez etiquetados, pueden acogerse a los beneficios previstos por la ley, adem\u00e1s de a los servicios Startup Ecosystem y Startup Invest.<\/p>\n<p>En 2020, la iniciativa SAVE se despleg\u00f3 r\u00e1pidamente a trav\u00e9s de Startup T\u00fanez para proteger a los emprendedores durante la pandemia de COVID-19. SAVE protegi\u00f3 a 60 empresas emergentes concedi\u00e9ndoles pr\u00e9stamos de emergencia de entre 10.000 TND (3.285 USD) y 50.000 TND (16.425 USD).<sup><a href=\"#policy-reference-10\">10<\/a><\/sup><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<h2><b><hgroup class=\"section-group\"><svg class='section-group__icon' aria-hidden='true' slot='caret'><use xlink:href='#sprite-cost'><\/use><\/svg><h2 class='section-group__heading'><\/b><b>Coste<\/b><b><\/h2><\/hgroup><\/b><\/h2>\n<p>Hay muchas iniciativas en el marco de Startup Ecosystem y Startup Invest, que movilizan fondos de diversas fuentes. La financiaci\u00f3n corre a cargo de la empresa estatal \u00abCaisse des D\u00e9p\u00f4ts et Consignations\u00bb, as\u00ed como de numerosos donantes. En 2019, el Banco Mundial concedi\u00f3 un pr\u00e9stamo de 75 millones de USD para apoyar el Proyecto Startup T\u00fanez.<sup><a href=\"#policy-reference-11\">11<\/a><\/sup> Expertise France proporcion\u00f3 583.000 EUR (643.000 USD) para la iniciativa de emergencia SAVE durante COVID-19.<sup><a href=\"#policy-reference-12\">12<\/a><\/sup><\/p>\n<h2><b><hgroup class=\"section-group\"><svg class='section-group__icon' aria-hidden='true' slot='caret'><use xlink:href='#sprite-assessment'><\/use><\/svg><h2 class='section-group__heading'><\/b><b>Evaluaci\u00f3n<\/b><b><\/h2><\/hgroup><\/b><a href=\"#_ftn4\" name=\"_ftnref4\"><\/a><\/h2>\n<p>A finales de 2021, Startup T\u00fanez hab\u00eda apoyado a 650 startups (el 65% del objetivo para 2024). Hab\u00eda contribuido a la creaci\u00f3n de 4.500 nuevos puestos de trabajo (el 45% del objetivo) y ten\u00eda un volumen de negocios acumulado de 240 millones de TND o 77 millones de USD (el 24% del objetivo).<sup><a href=\"#policy-reference-13\">13<\/a><\/sup> Adem\u00e1s, Startup Tunisia hab\u00eda apoyado a trece empresas emergentes tunecinas para que se introdujeran en los mercados internacionales.<sup><a href=\"#policy-reference-14\">14<\/a><\/sup><\/p>\n<p>La iniciativa ha contribuido a una mayor inclusi\u00f3n econ\u00f3mica de las mujeres y los j\u00f3venes. En 2020, la edad media del fundador de una startup era de treinta y cuatro a\u00f1os. Las mujeres cofundaron el 34% de las startups, y el 45% de los puestos de trabajo creados fueron ocupados por mujeres.<sup><a href=\"#policy-reference-15\">15<\/a><\/sup><\/p>\n<p>Aunque se han producido muchos avances positivos, Startup T\u00fanez reconoce que a\u00fan queda trabajo por hacer para empoderar a las mujeres y a las zonas rurales. Aunque el 45% de las empresas de nueva creaci\u00f3n fueron cofundadas por mujeres, s\u00f3lo el 5% fueron fundadas exclusivamente por mujeres.<sup><a href=\"#policy-reference-16\">16<\/a><\/sup> <a href=\"#_ftn4\" name=\"_ftnref4\"><\/a> Las mujeres siguen vi\u00e9ndose obstaculizadas por normas sociales y culturales que limitan su acceso al capital.<sup><a href=\"#policy-reference-17\">17<\/a><\/sup> Mientras tanto, en 2021 el 70% de las empresas de nueva creaci\u00f3n estaban ubicadas en T\u00fanez, la capital.<sup><a href=\"#policy-reference-18\">18<\/a><\/sup><\/p>\n<p>El marco jur\u00eddico de la Startup Act inspir\u00f3 a pa\u00edses como Ruanda, Senegal y Costa de Marfil a ratificar una legislaci\u00f3n similar para promover el esp\u00edritu empresarial en sus pa\u00edses.<sup><a href=\"#policy-reference-19\">19<\/a><\/sup><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/p>\n<h6>\u00a9Adobe Stock\/sodawhiskey<\/h6>\n<p><\/b><\/h2>\n<p><\/b><\/h2>\n","protected":false},"template":"","categories":[],"tags":[744,758,745,746,743,770,879],"class_list":["post-16088","policies","type-policies","status-publish","hentry","tag-genero","tag-infancia-y-juventud","tag-oriente-medio-y-norte-de-africa","tag-pais-de-renta-media","tag-renta-y-patrimonio","tag-trabajo","tag-tunez","policy-regions-middle-east-north-africa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apoyar el desempleo mediante la Startup Act: T\u00fanez - Pathfinders<\/title>\n<meta name=\"description\" content=\"Startup Act T\u00fanez: Legislaci\u00f3n y apoyo a las j\u00f3venes startups para promover el esp\u00edritu empresarial (2018-en curso)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sdg16.plus\/es\/policies\/apoyar-el-desempleo-mediante-la-startup-act-tunez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apoyar el desempleo mediante la Startup Act: T\u00fanez - Pathfinders\" \/>\n<meta property=\"og:description\" content=\"Startup Act T\u00fanez: Legislaci\u00f3n y apoyo a las j\u00f3venes startups para promover el esp\u00edritu empresarial (2018-en curso)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sdg16.plus\/es\/policies\/apoyar-el-desempleo-mediante-la-startup-act-tunez\/\" \/>\n<meta property=\"og:site_name\" content=\"Pathfinders\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-13T14:50:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/policies\\\/apoyar-el-desempleo-mediante-la-startup-act-tunez\\\/\",\"url\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/policies\\\/apoyar-el-desempleo-mediante-la-startup-act-tunez\\\/\",\"name\":\"Apoyar el desempleo mediante la Startup Act: T\u00fanez - Pathfinders\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/#website\"},\"datePublished\":\"2023-10-09T03:38:18+00:00\",\"dateModified\":\"2024-12-13T14:50:10+00:00\",\"description\":\"Startup Act T\u00fanez: Legislaci\u00f3n y apoyo a las j\u00f3venes startups para promover el esp\u00edritu empresarial (2018-en curso)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/policies\\\/apoyar-el-desempleo-mediante-la-startup-act-tunez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/policies\\\/apoyar-el-desempleo-mediante-la-startup-act-tunez\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/policies\\\/apoyar-el-desempleo-mediante-la-startup-act-tunez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apoyar el desempleo mediante la Startup Act: T\u00fanez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/\",\"name\":\"Pathfinders\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sdg16.plus\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apoyar el desempleo mediante la Startup Act: T\u00fanez - Pathfinders","description":"Startup Act T\u00fanez: Legislaci\u00f3n y apoyo a las j\u00f3venes startups para promover el esp\u00edritu empresarial (2018-en curso)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sdg16.plus\/es\/policies\/apoyar-el-desempleo-mediante-la-startup-act-tunez\/","og_locale":"es_ES","og_type":"article","og_title":"Apoyar el desempleo mediante la Startup Act: T\u00fanez - Pathfinders","og_description":"Startup Act T\u00fanez: Legislaci\u00f3n y apoyo a las j\u00f3venes startups para promover el esp\u00edritu empresarial (2018-en curso)","og_url":"https:\/\/www.sdg16.plus\/es\/policies\/apoyar-el-desempleo-mediante-la-startup-act-tunez\/","og_site_name":"Pathfinders","article_modified_time":"2024-12-13T14:50:10+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sdg16.plus\/es\/policies\/apoyar-el-desempleo-mediante-la-startup-act-tunez\/","url":"https:\/\/www.sdg16.plus\/es\/policies\/apoyar-el-desempleo-mediante-la-startup-act-tunez\/","name":"Apoyar el desempleo mediante la Startup Act: T\u00fanez - Pathfinders","isPartOf":{"@id":"https:\/\/www.sdg16.plus\/es\/#website"},"datePublished":"2023-10-09T03:38:18+00:00","dateModified":"2024-12-13T14:50:10+00:00","description":"Startup Act T\u00fanez: Legislaci\u00f3n y apoyo a las j\u00f3venes startups para promover el esp\u00edritu empresarial (2018-en curso)","breadcrumb":{"@id":"https:\/\/www.sdg16.plus\/es\/policies\/apoyar-el-desempleo-mediante-la-startup-act-tunez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sdg16.plus\/es\/policies\/apoyar-el-desempleo-mediante-la-startup-act-tunez\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sdg16.plus\/es\/policies\/apoyar-el-desempleo-mediante-la-startup-act-tunez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sdg16.plus\/es\/"},{"@type":"ListItem","position":2,"name":"Apoyar el desempleo mediante la Startup Act: T\u00fanez"}]},{"@type":"WebSite","@id":"https:\/\/www.sdg16.plus\/es\/#website","url":"https:\/\/www.sdg16.plus\/es\/","name":"Pathfinders","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sdg16.plus\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.sdg16.plus\/es\/wp-json\/wp\/v2\/policies\/16088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sdg16.plus\/es\/wp-json\/wp\/v2\/policies"}],"about":[{"href":"https:\/\/www.sdg16.plus\/es\/wp-json\/wp\/v2\/types\/policies"}],"wp:attachment":[{"href":"https:\/\/www.sdg16.plus\/es\/wp-json\/wp\/v2\/media?parent=16088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sdg16.plus\/es\/wp-json\/wp\/v2\/categories?post=16088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sdg16.plus\/es\/wp-json\/wp\/v2\/tags?post=16088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}